{"id":7085,"date":"2026-03-09T15:38:59","date_gmt":"2026-03-09T14:38:59","guid":{"rendered":"https:\/\/www.uniontrento.it\/?p=7085"},"modified":"2026-03-09T15:47:20","modified_gmt":"2026-03-09T14:47:20","slug":"barbe-e-tornato","status":"publish","type":"post","link":"https:\/\/www.uniontrento.it\/index.php\/barbe-e-tornato\/","title":{"rendered":"Barbe \u00e8 tornato!"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Vittoria sofferta ma meritata per i ragazzi<\/h2>\n\n\n\n<p>Torniamo da Bressanone, sede del match con il fanalino di coda Gherdenia, con tre punti importanti per la classifica e con molti spunti per migliorare le nostre prestazioni e, soprattutto, per non soffrire cos\u00ec per vincere partite dominate per lunghi tratti. E&#8217; stato infatti un rocambolesco gol in contropiede al minuto 95&#8242; a risolvere per noi la gara del 22\u00b0 turno del Campionato di Eccellenza. <\/p>\n\n\n\n<p>Partiamo dal primo tempo, dominato in lungo e in largo dai ragazzi del Presidente Stanchina che potrebbero gi\u00e0 essere in largo vantaggio nella prima frazione di gioco: due le occasioni per Garcia gi\u00e0 nei primi sei minuti respinte dal portiere di casa la prima e dall&#8217;incrocio dei pali la seconda. Al minuto 28 prima il portiere compie un mezzo miracolo su Barbetti e poi \u00e8 Malfer a mettere colamorosamente a lato da due metri. Finalmente al 33\u00b0 minuto doppio triangolo tra Garcia e le due punte e il nostro fantasista numero 10 ci porta finalmente in vantaggio. Prima dell&#8217; intervallo si registra il decimo gol stagionale di Malfer che mette in porta di prepotenza una palla di Garcia, e una brillante parata di T. Melone su Vinatzer che ci porta alla sosta con due gol di vantaggio. Primo tempo: otto palle gol a una e risultato, bugiardo, di due a zero per i nostri, oggi in maglia blu. <\/p>\n\n\n\n<p>La ripresa si apre con tre minuti di follia della difesa trentina e un uno due tremendo ad opera dei gardenesi, dapprima con un colpo di testa in tuffo di Vinatzer, il migliore dei bianchi di mister Rella, e in seguito con una conclusione imparabile sotto misura di Rifesser in seguito ad una percussione sulla destra. Il clamoroso pareggio, del tutto inaspettato, non cambia la partita: sempre in avanti i nostri e in copertura con poche azioni di rimessa i padroni di casa.Al tredicesimo calcio d&#8217;angolo di Garcia, spizza sul primo palo Rizzon e in mischia risolve Dsiri che sigla il 2-3. <\/p>\n\n\n\n<p>La squadra di casa sembra subire il nuovo svantaggio ma alla mezzora, di nuovo Vinatzer \u00e8 atterrato in area: rigore che Volino trasforma. Ma non finisce cos\u00ec. Infatti al minuto 95, nell&#8217;ultima azione del match Garcia viene steso in contropiede ma l&#8217;arbitro concede il vantaggio a Bernardi che si invola e appoggia per Barbetti, piatto all&#8217;incrocio a scavalcare sopra il portiere e la truppa di mister M. Melone vince la partita. Trenta punti in saccoccia dopo ventun giornate e si torna a casa felici con il ritorno al gol di Barbetti.<\/p>\n\n\n\n<p><strong>Le formazioni<\/strong><\/p>\n\n\n\n<p><strong>Gherdeina<\/strong>: Stolz, Tiozzo (dal 69&#8242; Moroder), Angerer, Perathoner, Brentel, Rifesser, Senoner (dal 61&#8242; Abdenaim), Soghei, Demetz (dal 60&#8242; Masha), Vinatzer, Volino. <strong>Allenatore<\/strong> Rella<\/p>\n\n\n\n<p><strong>Union Trento<\/strong>: Melone M., Coslop, Yassir, Rizzon, Vitti (dal 55&#8217;Bernardi) Paoli, Pancheri, Ischia(dal 75&#8242; Mallemace), Garcia, Barbetti, Malfer (dal 60&#8242; Comper). <strong>Allenatore<\/strong> Marco Melone <\/p>\n\n\n\n<p><strong>Arbitro<\/strong>: Pintarelli di Bolzano ( Cotroneo e Paparella) <\/p>\n\n\n\n<p><strong>Marcatori <\/strong>: al 33&#8242; Garcia (UT), al 43&#8242; Malfer (UT), al 47&#8242; Vinatzer (GH), al 49&#8242; Rifesser (GH), al 59&#8242; Dsiri (UT), al 75&#8242; Volino (GH), al 95&#8242; Barbetti (UT)<\/p>\n\n\n\n<p><a href=\"https:\/\/youtu.be\/NyoJgKJqGdU\">IL GOL PARTITA DI BOMBER BARBETTI<\/a><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"718\" src=\"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2026\/03\/UNIONSTGEORGEN-51-1024x718.jpg\" alt=\"\" class=\"wp-image-7090\" srcset=\"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2026\/03\/UNIONSTGEORGEN-51-1024x718.jpg 1024w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2026\/03\/UNIONSTGEORGEN-51-300x210.jpg 300w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2026\/03\/UNIONSTGEORGEN-51-768x539.jpg 768w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2026\/03\/UNIONSTGEORGEN-51-1536x1077.jpg 1536w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2026\/03\/UNIONSTGEORGEN-51-2048x1436.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Vittoria sofferta ma meritata per i ragazzi Torniamo da Bressanone, sede del match con il fanalino di coda Gherdenia, con tre punti importanti per la classifica e con molti spunti per migliorare le nostre prestazioni e, soprattutto, per non soffrire cos\u00ec per vincere partite dominate per lunghi tratti. E&#8217; stato infatti un rocambolesco gol in [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":7097,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-7085","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ravinense"],"blocksy_meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Barbe \u00e8 tornato! - Union Trento - Official Site % %<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.uniontrento.it\/index.php\/barbe-e-tornato\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Barbe \u00e8 tornato! - Union Trento - Official Site % %\" \/>\n<meta property=\"og:description\" content=\"Vittoria sofferta ma meritata per i ragazzi Torniamo da Bressanone, sede del match con il fanalino di coda Gherdenia, con tre punti importanti per la classifica e con molti spunti per migliorare le nostre prestazioni e, soprattutto, per non soffrire cos\u00ec per vincere partite dominate per lunghi tratti. E&#8217; stato infatti un rocambolesco gol in [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.uniontrento.it\/index.php\/barbe-e-tornato\/\" \/>\n<meta property=\"og:site_name\" content=\"Union Trento - Official Site\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/UnionTrento\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-09T14:38:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-09T14:47:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2026\/03\/Barbetti.png\" \/>\n\t<meta property=\"og:image:width\" content=\"499\" \/>\n\t<meta property=\"og:image:height\" content=\"396\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"uniontrento_gestioneweb\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"uniontrento_gestioneweb\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/index.php\\\/barbe-e-tornato\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/index.php\\\/barbe-e-tornato\\\/\"},\"author\":{\"name\":\"uniontrento_gestioneweb\",\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/#\\\/schema\\\/person\\\/0c6508e49b2f6ca9fb8db40660ad9188\"},\"headline\":\"Barbe \u00e8 tornato!\",\"datePublished\":\"2026-03-09T14:38:59+00:00\",\"dateModified\":\"2026-03-09T14:47:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/index.php\\\/barbe-e-tornato\\\/\"},\"wordCount\":503,\"publisher\":{\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/index.php\\\/barbe-e-tornato\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.uniontrento.it\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Barbetti.png\",\"articleSection\":[\"News Union Trento Ravinense\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/index.php\\\/barbe-e-tornato\\\/\",\"url\":\"https:\\\/\\\/www.uniontrento.it\\\/index.php\\\/barbe-e-tornato\\\/\",\"name\":\"Barbe \u00e8 tornato! - Union Trento - Official Site % %\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/index.php\\\/barbe-e-tornato\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/index.php\\\/barbe-e-tornato\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.uniontrento.it\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Barbetti.png\",\"datePublished\":\"2026-03-09T14:38:59+00:00\",\"dateModified\":\"2026-03-09T14:47:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/index.php\\\/barbe-e-tornato\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.uniontrento.it\\\/index.php\\\/barbe-e-tornato\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/index.php\\\/barbe-e-tornato\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.uniontrento.it\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Barbetti.png\",\"contentUrl\":\"https:\\\/\\\/www.uniontrento.it\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Barbetti.png\",\"width\":499,\"height\":396},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/index.php\\\/barbe-e-tornato\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.uniontrento.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Barbe \u00e8 tornato!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/#website\",\"url\":\"https:\\\/\\\/www.uniontrento.it\\\/\",\"name\":\"Union Trento\",\"description\":\"Sito ufficiale Union Trento, nuovo progetto calcistico nella citt\u00e0 di Trento che incorpora le societ\u00e0 Mattarello Calcio e U.S. Ravinense\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.uniontrento.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/#organization\",\"name\":\"Union Trento\",\"url\":\"https:\\\/\\\/www.uniontrento.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.uniontrento.it\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/LogoUnionTrento_col.png\",\"contentUrl\":\"https:\\\/\\\/www.uniontrento.it\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/LogoUnionTrento_col.png\",\"width\":924,\"height\":1198,\"caption\":\"Union Trento\"},\"image\":{\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/UnionTrento\",\"https:\\\/\\\/www.instagram.com\\\/union_trento\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/#\\\/schema\\\/person\\\/0c6508e49b2f6ca9fb8db40660ad9188\",\"name\":\"uniontrento_gestioneweb\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/78920b74754d8edf774bf4174042990997a633859907c226bc7056921d103849?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/78920b74754d8edf774bf4174042990997a633859907c226bc7056921d103849?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/78920b74754d8edf774bf4174042990997a633859907c226bc7056921d103849?s=96&d=mm&r=g\",\"caption\":\"uniontrento_gestioneweb\"},\"url\":\"https:\\\/\\\/www.uniontrento.it\\\/index.php\\\/author\\\/uniontrento_gestioneweb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Barbe \u00e8 tornato! - Union Trento - Official Site % %","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.uniontrento.it\/index.php\/barbe-e-tornato\/","og_locale":"it_IT","og_type":"article","og_title":"Barbe \u00e8 tornato! - Union Trento - Official Site % %","og_description":"Vittoria sofferta ma meritata per i ragazzi Torniamo da Bressanone, sede del match con il fanalino di coda Gherdenia, con tre punti importanti per la classifica e con molti spunti per migliorare le nostre prestazioni e, soprattutto, per non soffrire cos\u00ec per vincere partite dominate per lunghi tratti. E&#8217; stato infatti un rocambolesco gol in [&hellip;]","og_url":"https:\/\/www.uniontrento.it\/index.php\/barbe-e-tornato\/","og_site_name":"Union Trento - Official Site","article_publisher":"https:\/\/www.facebook.com\/UnionTrento","article_published_time":"2026-03-09T14:38:59+00:00","article_modified_time":"2026-03-09T14:47:20+00:00","og_image":[{"width":499,"height":396,"url":"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2026\/03\/Barbetti.png","type":"image\/png"}],"author":"uniontrento_gestioneweb","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"uniontrento_gestioneweb","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.uniontrento.it\/index.php\/barbe-e-tornato\/#article","isPartOf":{"@id":"https:\/\/www.uniontrento.it\/index.php\/barbe-e-tornato\/"},"author":{"name":"uniontrento_gestioneweb","@id":"https:\/\/www.uniontrento.it\/#\/schema\/person\/0c6508e49b2f6ca9fb8db40660ad9188"},"headline":"Barbe \u00e8 tornato!","datePublished":"2026-03-09T14:38:59+00:00","dateModified":"2026-03-09T14:47:20+00:00","mainEntityOfPage":{"@id":"https:\/\/www.uniontrento.it\/index.php\/barbe-e-tornato\/"},"wordCount":503,"publisher":{"@id":"https:\/\/www.uniontrento.it\/#organization"},"image":{"@id":"https:\/\/www.uniontrento.it\/index.php\/barbe-e-tornato\/#primaryimage"},"thumbnailUrl":"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2026\/03\/Barbetti.png","articleSection":["News Union Trento Ravinense"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.uniontrento.it\/index.php\/barbe-e-tornato\/","url":"https:\/\/www.uniontrento.it\/index.php\/barbe-e-tornato\/","name":"Barbe \u00e8 tornato! - Union Trento - Official Site % %","isPartOf":{"@id":"https:\/\/www.uniontrento.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.uniontrento.it\/index.php\/barbe-e-tornato\/#primaryimage"},"image":{"@id":"https:\/\/www.uniontrento.it\/index.php\/barbe-e-tornato\/#primaryimage"},"thumbnailUrl":"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2026\/03\/Barbetti.png","datePublished":"2026-03-09T14:38:59+00:00","dateModified":"2026-03-09T14:47:20+00:00","breadcrumb":{"@id":"https:\/\/www.uniontrento.it\/index.php\/barbe-e-tornato\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.uniontrento.it\/index.php\/barbe-e-tornato\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.uniontrento.it\/index.php\/barbe-e-tornato\/#primaryimage","url":"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2026\/03\/Barbetti.png","contentUrl":"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2026\/03\/Barbetti.png","width":499,"height":396},{"@type":"BreadcrumbList","@id":"https:\/\/www.uniontrento.it\/index.php\/barbe-e-tornato\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.uniontrento.it\/"},{"@type":"ListItem","position":2,"name":"Barbe \u00e8 tornato!"}]},{"@type":"WebSite","@id":"https:\/\/www.uniontrento.it\/#website","url":"https:\/\/www.uniontrento.it\/","name":"Union Trento","description":"Sito ufficiale Union Trento, nuovo progetto calcistico nella citt\u00e0 di Trento che incorpora le societ\u00e0 Mattarello Calcio e U.S. Ravinense","publisher":{"@id":"https:\/\/www.uniontrento.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.uniontrento.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.uniontrento.it\/#organization","name":"Union Trento","url":"https:\/\/www.uniontrento.it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.uniontrento.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2024\/08\/LogoUnionTrento_col.png","contentUrl":"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2024\/08\/LogoUnionTrento_col.png","width":924,"height":1198,"caption":"Union Trento"},"image":{"@id":"https:\/\/www.uniontrento.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/UnionTrento","https:\/\/www.instagram.com\/union_trento\/"]},{"@type":"Person","@id":"https:\/\/www.uniontrento.it\/#\/schema\/person\/0c6508e49b2f6ca9fb8db40660ad9188","name":"uniontrento_gestioneweb","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/78920b74754d8edf774bf4174042990997a633859907c226bc7056921d103849?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/78920b74754d8edf774bf4174042990997a633859907c226bc7056921d103849?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/78920b74754d8edf774bf4174042990997a633859907c226bc7056921d103849?s=96&d=mm&r=g","caption":"uniontrento_gestioneweb"},"url":"https:\/\/www.uniontrento.it\/index.php\/author\/uniontrento_gestioneweb\/"}]}},"_links":{"self":[{"href":"https:\/\/www.uniontrento.it\/index.php\/wp-json\/wp\/v2\/posts\/7085","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uniontrento.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uniontrento.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uniontrento.it\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uniontrento.it\/index.php\/wp-json\/wp\/v2\/comments?post=7085"}],"version-history":[{"count":1,"href":"https:\/\/www.uniontrento.it\/index.php\/wp-json\/wp\/v2\/posts\/7085\/revisions"}],"predecessor-version":[{"id":7093,"href":"https:\/\/www.uniontrento.it\/index.php\/wp-json\/wp\/v2\/posts\/7085\/revisions\/7093"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.uniontrento.it\/index.php\/wp-json\/wp\/v2\/media\/7097"}],"wp:attachment":[{"href":"https:\/\/www.uniontrento.it\/index.php\/wp-json\/wp\/v2\/media?parent=7085"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uniontrento.it\/index.php\/wp-json\/wp\/v2\/categories?post=7085"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uniontrento.it\/index.php\/wp-json\/wp\/v2\/tags?post=7085"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}