{"id":6314,"date":"2025-08-15T21:13:19","date_gmt":"2025-08-15T19:13:19","guid":{"rendered":"https:\/\/www.uniontrento.it\/?p=6314"},"modified":"2025-08-15T21:13:19","modified_gmt":"2025-08-15T19:13:19","slug":"netta-vittoria-sul-salorno-prima-della-pausa-di-ferragosto","status":"publish","type":"post","link":"https:\/\/www.uniontrento.it\/index.php\/netta-vittoria-sul-salorno-prima-della-pausa-di-ferragosto\/","title":{"rendered":"NETTA VITTORIA SUL SALORNO PRIMA DELLA PAUSA DI FERRAGOSTO"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Barbetti e Malfer affondano un ottimo Salorno, squadra di promozione altoatesina<\/h2>\n\n\n\n<p><\/p>\n\n\n\n<p>Prima della mini pausa di tre giorni concessa da Mister Melone per il Ferragosto, l&#8217;Union Trento si impone per 3 a 1 sul manto erboso di Salorno, nella penultima amichevole prima dell&#8217;inizio delle gare ufficiali. La squadra \u00e8 sembrata ancora in crescita, con meccanismi e affiatamento che crescono giorno dopo giorno. A segno i due Bomber principe, doppietta di Barbetti nel primo tempo e sigillo finale di Malfer. Prossimo impegno amichevole marted\u00ec con il Borgo di Mister Floriani.<\/p>\n\n\n\n<p>Formazione I Tempo: Kodra, Coslop, Gretter, Eccheli, Vitti, Orsega, Pancheri, fFerrari, Garcia, Barbetti, Bisognin<\/p>\n\n\n\n<p>Formazione II tempo: Kodra (dal 60&#8242; Melone), Gretter (dal 70&#8242; Cristofori), Pancheri, Eccheli (dal 60&#8242; Maran), Chemolli, , Paoli, Bernardi, Comper, Malfer, Garcia (dal 60&#8242; Pintarelli)<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"724\" height=\"1024\" data-id=\"6318\" src=\"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/08\/Barbe-724x1024.png\" alt=\"\" class=\"wp-image-6318\" srcset=\"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/08\/Barbe-724x1024.png 724w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/08\/Barbe-212x300.png 212w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/08\/Barbe-768x1087.png 768w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/08\/Barbe-1085x1536.png 1085w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/08\/Barbe-1447x2048.png 1447w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/08\/Barbe.png 1900w\" sizes=\"(max-width: 724px) 100vw, 724px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"894\" height=\"1024\" data-id=\"6317\" src=\"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/08\/Malfer-894x1024.png\" alt=\"\" class=\"wp-image-6317\" srcset=\"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/08\/Malfer-894x1024.png 894w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/08\/Malfer-262x300.png 262w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/08\/Malfer-768x879.png 768w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/08\/Malfer-1342x1536.png 1342w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/08\/Malfer-1789x2048.png 1789w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/08\/Malfer.png 1863w\" sizes=\"(max-width: 894px) 100vw, 894px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Barbetti e Malfer affondano un ottimo Salorno, squadra di promozione altoatesina Prima della mini pausa di tre giorni concessa da Mister Melone per il Ferragosto, l&#8217;Union Trento si impone per 3 a 1 sul manto erboso di Salorno, nella penultima amichevole prima dell&#8217;inizio delle gare ufficiali. La squadra \u00e8 sembrata ancora in crescita, con meccanismi [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":6319,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-6314","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ravinense"],"blocksy_meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>NETTA VITTORIA SUL SALORNO PRIMA DELLA PAUSA DI FERRAGOSTO - Union Trento - Official Site % %<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.uniontrento.it\/index.php\/netta-vittoria-sul-salorno-prima-della-pausa-di-ferragosto\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"NETTA VITTORIA SUL SALORNO PRIMA DELLA PAUSA DI FERRAGOSTO - Union Trento - Official Site % %\" \/>\n<meta property=\"og:description\" content=\"Barbetti e Malfer affondano un ottimo Salorno, squadra di promozione altoatesina Prima della mini pausa di tre giorni concessa da Mister Melone per il Ferragosto, l&#8217;Union Trento si impone per 3 a 1 sul manto erboso di Salorno, nella penultima amichevole prima dell&#8217;inizio delle gare ufficiali. La squadra \u00e8 sembrata ancora in crescita, con meccanismi [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.uniontrento.it\/index.php\/netta-vittoria-sul-salorno-prima-della-pausa-di-ferragosto\/\" \/>\n<meta property=\"og:site_name\" content=\"Union Trento - Official Site\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/UnionTrento\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-15T19:13:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/08\/Barbe1-1024x544.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"544\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"uniontrento_gestioneweb\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"uniontrento_gestioneweb\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/index.php\\\/netta-vittoria-sul-salorno-prima-della-pausa-di-ferragosto\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/index.php\\\/netta-vittoria-sul-salorno-prima-della-pausa-di-ferragosto\\\/\"},\"author\":{\"name\":\"uniontrento_gestioneweb\",\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/#\\\/schema\\\/person\\\/0c6508e49b2f6ca9fb8db40660ad9188\"},\"headline\":\"NETTA VITTORIA SUL SALORNO PRIMA DELLA PAUSA DI FERRAGOSTO\",\"datePublished\":\"2025-08-15T19:13:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/index.php\\\/netta-vittoria-sul-salorno-prima-della-pausa-di-ferragosto\\\/\"},\"wordCount\":132,\"publisher\":{\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/index.php\\\/netta-vittoria-sul-salorno-prima-della-pausa-di-ferragosto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.uniontrento.it\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Barbe1.png\",\"articleSection\":[\"News Union Trento Ravinense\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/index.php\\\/netta-vittoria-sul-salorno-prima-della-pausa-di-ferragosto\\\/\",\"url\":\"https:\\\/\\\/www.uniontrento.it\\\/index.php\\\/netta-vittoria-sul-salorno-prima-della-pausa-di-ferragosto\\\/\",\"name\":\"NETTA VITTORIA SUL SALORNO PRIMA DELLA PAUSA DI FERRAGOSTO - Union Trento - Official Site % %\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/index.php\\\/netta-vittoria-sul-salorno-prima-della-pausa-di-ferragosto\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/index.php\\\/netta-vittoria-sul-salorno-prima-della-pausa-di-ferragosto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.uniontrento.it\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Barbe1.png\",\"datePublished\":\"2025-08-15T19:13:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/index.php\\\/netta-vittoria-sul-salorno-prima-della-pausa-di-ferragosto\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.uniontrento.it\\\/index.php\\\/netta-vittoria-sul-salorno-prima-della-pausa-di-ferragosto\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/index.php\\\/netta-vittoria-sul-salorno-prima-della-pausa-di-ferragosto\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.uniontrento.it\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Barbe1.png\",\"contentUrl\":\"https:\\\/\\\/www.uniontrento.it\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Barbe1.png\",\"width\":3760,\"height\":1996},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/index.php\\\/netta-vittoria-sul-salorno-prima-della-pausa-di-ferragosto\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.uniontrento.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NETTA VITTORIA SUL SALORNO PRIMA DELLA PAUSA DI FERRAGOSTO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/#website\",\"url\":\"https:\\\/\\\/www.uniontrento.it\\\/\",\"name\":\"Union Trento\",\"description\":\"Sito ufficiale Union Trento, nuovo progetto calcistico nella citt\u00e0 di Trento che incorpora le societ\u00e0 Mattarello Calcio e U.S. Ravinense\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.uniontrento.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/#organization\",\"name\":\"Union Trento\",\"url\":\"https:\\\/\\\/www.uniontrento.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.uniontrento.it\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/LogoUnionTrento_col.png\",\"contentUrl\":\"https:\\\/\\\/www.uniontrento.it\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/LogoUnionTrento_col.png\",\"width\":924,\"height\":1198,\"caption\":\"Union Trento\"},\"image\":{\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/UnionTrento\",\"https:\\\/\\\/www.instagram.com\\\/union_trento\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/#\\\/schema\\\/person\\\/0c6508e49b2f6ca9fb8db40660ad9188\",\"name\":\"uniontrento_gestioneweb\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/78920b74754d8edf774bf4174042990997a633859907c226bc7056921d103849?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/78920b74754d8edf774bf4174042990997a633859907c226bc7056921d103849?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/78920b74754d8edf774bf4174042990997a633859907c226bc7056921d103849?s=96&d=mm&r=g\",\"caption\":\"uniontrento_gestioneweb\"},\"url\":\"https:\\\/\\\/www.uniontrento.it\\\/index.php\\\/author\\\/uniontrento_gestioneweb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"NETTA VITTORIA SUL SALORNO PRIMA DELLA PAUSA DI FERRAGOSTO - Union Trento - Official Site % %","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.uniontrento.it\/index.php\/netta-vittoria-sul-salorno-prima-della-pausa-di-ferragosto\/","og_locale":"it_IT","og_type":"article","og_title":"NETTA VITTORIA SUL SALORNO PRIMA DELLA PAUSA DI FERRAGOSTO - Union Trento - Official Site % %","og_description":"Barbetti e Malfer affondano un ottimo Salorno, squadra di promozione altoatesina Prima della mini pausa di tre giorni concessa da Mister Melone per il Ferragosto, l&#8217;Union Trento si impone per 3 a 1 sul manto erboso di Salorno, nella penultima amichevole prima dell&#8217;inizio delle gare ufficiali. La squadra \u00e8 sembrata ancora in crescita, con meccanismi [&hellip;]","og_url":"https:\/\/www.uniontrento.it\/index.php\/netta-vittoria-sul-salorno-prima-della-pausa-di-ferragosto\/","og_site_name":"Union Trento - Official Site","article_publisher":"https:\/\/www.facebook.com\/UnionTrento","article_published_time":"2025-08-15T19:13:19+00:00","og_image":[{"width":1024,"height":544,"url":"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/08\/Barbe1-1024x544.png","type":"image\/png"}],"author":"uniontrento_gestioneweb","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"uniontrento_gestioneweb","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.uniontrento.it\/index.php\/netta-vittoria-sul-salorno-prima-della-pausa-di-ferragosto\/#article","isPartOf":{"@id":"https:\/\/www.uniontrento.it\/index.php\/netta-vittoria-sul-salorno-prima-della-pausa-di-ferragosto\/"},"author":{"name":"uniontrento_gestioneweb","@id":"https:\/\/www.uniontrento.it\/#\/schema\/person\/0c6508e49b2f6ca9fb8db40660ad9188"},"headline":"NETTA VITTORIA SUL SALORNO PRIMA DELLA PAUSA DI FERRAGOSTO","datePublished":"2025-08-15T19:13:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.uniontrento.it\/index.php\/netta-vittoria-sul-salorno-prima-della-pausa-di-ferragosto\/"},"wordCount":132,"publisher":{"@id":"https:\/\/www.uniontrento.it\/#organization"},"image":{"@id":"https:\/\/www.uniontrento.it\/index.php\/netta-vittoria-sul-salorno-prima-della-pausa-di-ferragosto\/#primaryimage"},"thumbnailUrl":"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/08\/Barbe1.png","articleSection":["News Union Trento Ravinense"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.uniontrento.it\/index.php\/netta-vittoria-sul-salorno-prima-della-pausa-di-ferragosto\/","url":"https:\/\/www.uniontrento.it\/index.php\/netta-vittoria-sul-salorno-prima-della-pausa-di-ferragosto\/","name":"NETTA VITTORIA SUL SALORNO PRIMA DELLA PAUSA DI FERRAGOSTO - Union Trento - Official Site % %","isPartOf":{"@id":"https:\/\/www.uniontrento.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.uniontrento.it\/index.php\/netta-vittoria-sul-salorno-prima-della-pausa-di-ferragosto\/#primaryimage"},"image":{"@id":"https:\/\/www.uniontrento.it\/index.php\/netta-vittoria-sul-salorno-prima-della-pausa-di-ferragosto\/#primaryimage"},"thumbnailUrl":"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/08\/Barbe1.png","datePublished":"2025-08-15T19:13:19+00:00","breadcrumb":{"@id":"https:\/\/www.uniontrento.it\/index.php\/netta-vittoria-sul-salorno-prima-della-pausa-di-ferragosto\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.uniontrento.it\/index.php\/netta-vittoria-sul-salorno-prima-della-pausa-di-ferragosto\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.uniontrento.it\/index.php\/netta-vittoria-sul-salorno-prima-della-pausa-di-ferragosto\/#primaryimage","url":"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/08\/Barbe1.png","contentUrl":"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/08\/Barbe1.png","width":3760,"height":1996},{"@type":"BreadcrumbList","@id":"https:\/\/www.uniontrento.it\/index.php\/netta-vittoria-sul-salorno-prima-della-pausa-di-ferragosto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.uniontrento.it\/"},{"@type":"ListItem","position":2,"name":"NETTA VITTORIA SUL SALORNO PRIMA DELLA PAUSA DI FERRAGOSTO"}]},{"@type":"WebSite","@id":"https:\/\/www.uniontrento.it\/#website","url":"https:\/\/www.uniontrento.it\/","name":"Union Trento","description":"Sito ufficiale Union Trento, nuovo progetto calcistico nella citt\u00e0 di Trento che incorpora le societ\u00e0 Mattarello Calcio e U.S. Ravinense","publisher":{"@id":"https:\/\/www.uniontrento.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.uniontrento.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.uniontrento.it\/#organization","name":"Union Trento","url":"https:\/\/www.uniontrento.it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.uniontrento.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2024\/08\/LogoUnionTrento_col.png","contentUrl":"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2024\/08\/LogoUnionTrento_col.png","width":924,"height":1198,"caption":"Union Trento"},"image":{"@id":"https:\/\/www.uniontrento.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/UnionTrento","https:\/\/www.instagram.com\/union_trento\/"]},{"@type":"Person","@id":"https:\/\/www.uniontrento.it\/#\/schema\/person\/0c6508e49b2f6ca9fb8db40660ad9188","name":"uniontrento_gestioneweb","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/78920b74754d8edf774bf4174042990997a633859907c226bc7056921d103849?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/78920b74754d8edf774bf4174042990997a633859907c226bc7056921d103849?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/78920b74754d8edf774bf4174042990997a633859907c226bc7056921d103849?s=96&d=mm&r=g","caption":"uniontrento_gestioneweb"},"url":"https:\/\/www.uniontrento.it\/index.php\/author\/uniontrento_gestioneweb\/"}]}},"_links":{"self":[{"href":"https:\/\/www.uniontrento.it\/index.php\/wp-json\/wp\/v2\/posts\/6314","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uniontrento.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uniontrento.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uniontrento.it\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uniontrento.it\/index.php\/wp-json\/wp\/v2\/comments?post=6314"}],"version-history":[{"count":1,"href":"https:\/\/www.uniontrento.it\/index.php\/wp-json\/wp\/v2\/posts\/6314\/revisions"}],"predecessor-version":[{"id":6320,"href":"https:\/\/www.uniontrento.it\/index.php\/wp-json\/wp\/v2\/posts\/6314\/revisions\/6320"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.uniontrento.it\/index.php\/wp-json\/wp\/v2\/media\/6319"}],"wp:attachment":[{"href":"https:\/\/www.uniontrento.it\/index.php\/wp-json\/wp\/v2\/media?parent=6314"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uniontrento.it\/index.php\/wp-json\/wp\/v2\/categories?post=6314"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uniontrento.it\/index.php\/wp-json\/wp\/v2\/tags?post=6314"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}