{"id":6270,"date":"2025-08-13T15:47:54","date_gmt":"2025-08-13T13:47:54","guid":{"rendered":"https:\/\/www.uniontrento.it\/?p=6270"},"modified":"2025-08-13T15:47:55","modified_gmt":"2025-08-13T13:47:55","slug":"giornale-il-t-quotidiano","status":"publish","type":"post","link":"https:\/\/www.uniontrento.it\/index.php\/giornale-il-t-quotidiano\/","title":{"rendered":"Giornale Il T Quotidiano"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large is-resized\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"721\" src=\"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/08\/Il-T-1024x721.jpg\" alt=\"\" class=\"wp-image-6271\" style=\"width:1301px;height:auto\" srcset=\"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/08\/Il-T-1024x721.jpg 1024w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/08\/Il-T-300x211.jpg 300w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/08\/Il-T-768x541.jpg 768w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/08\/Il-T.jpg 1440w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":6272,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[31],"tags":[],"class_list":["post-6270","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rass-stampa-usravinense"],"blocksy_meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Giornale Il T Quotidiano - Union Trento - Official Site % %<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.uniontrento.it\/index.php\/giornale-il-t-quotidiano\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Giornale Il T Quotidiano - Union Trento - Official Site % %\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.uniontrento.it\/index.php\/giornale-il-t-quotidiano\/\" \/>\n<meta property=\"og:site_name\" content=\"Union Trento - Official Site\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/UnionTrento\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-13T13:47:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-13T13:47:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/08\/Panco-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1218\" \/>\n\t<meta property=\"og:image:height\" content=\"867\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"uniontrento_gestioneweb\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"uniontrento_gestioneweb\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/index.php\\\/giornale-il-t-quotidiano\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/index.php\\\/giornale-il-t-quotidiano\\\/\"},\"author\":{\"name\":\"uniontrento_gestioneweb\",\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/#\\\/schema\\\/person\\\/0c6508e49b2f6ca9fb8db40660ad9188\"},\"headline\":\"Giornale Il T Quotidiano\",\"datePublished\":\"2025-08-13T13:47:54+00:00\",\"dateModified\":\"2025-08-13T13:47:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/index.php\\\/giornale-il-t-quotidiano\\\/\"},\"wordCount\":4,\"publisher\":{\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/index.php\\\/giornale-il-t-quotidiano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.uniontrento.it\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Panco-1.png\",\"articleSection\":[\"Rassegna stampa - Union Trento Ravinense\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/index.php\\\/giornale-il-t-quotidiano\\\/\",\"url\":\"https:\\\/\\\/www.uniontrento.it\\\/index.php\\\/giornale-il-t-quotidiano\\\/\",\"name\":\"Giornale Il T Quotidiano - Union Trento - Official Site % %\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/index.php\\\/giornale-il-t-quotidiano\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/index.php\\\/giornale-il-t-quotidiano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.uniontrento.it\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Panco-1.png\",\"datePublished\":\"2025-08-13T13:47:54+00:00\",\"dateModified\":\"2025-08-13T13:47:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/index.php\\\/giornale-il-t-quotidiano\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.uniontrento.it\\\/index.php\\\/giornale-il-t-quotidiano\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/index.php\\\/giornale-il-t-quotidiano\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.uniontrento.it\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Panco-1.png\",\"contentUrl\":\"https:\\\/\\\/www.uniontrento.it\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Panco-1.png\",\"width\":1218,\"height\":867},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/index.php\\\/giornale-il-t-quotidiano\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.uniontrento.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Giornale Il T Quotidiano\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/#website\",\"url\":\"https:\\\/\\\/www.uniontrento.it\\\/\",\"name\":\"Union Trento\",\"description\":\"Sito ufficiale Union Trento, nuovo progetto calcistico nella citt\u00e0 di Trento che incorpora le societ\u00e0 Mattarello Calcio e U.S. Ravinense\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.uniontrento.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/#organization\",\"name\":\"Union Trento\",\"url\":\"https:\\\/\\\/www.uniontrento.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.uniontrento.it\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/LogoUnionTrento_col.png\",\"contentUrl\":\"https:\\\/\\\/www.uniontrento.it\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/LogoUnionTrento_col.png\",\"width\":924,\"height\":1198,\"caption\":\"Union Trento\"},\"image\":{\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/UnionTrento\",\"https:\\\/\\\/www.instagram.com\\\/union_trento\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/#\\\/schema\\\/person\\\/0c6508e49b2f6ca9fb8db40660ad9188\",\"name\":\"uniontrento_gestioneweb\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/78920b74754d8edf774bf4174042990997a633859907c226bc7056921d103849?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/78920b74754d8edf774bf4174042990997a633859907c226bc7056921d103849?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/78920b74754d8edf774bf4174042990997a633859907c226bc7056921d103849?s=96&d=mm&r=g\",\"caption\":\"uniontrento_gestioneweb\"},\"url\":\"https:\\\/\\\/www.uniontrento.it\\\/index.php\\\/author\\\/uniontrento_gestioneweb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Giornale Il T Quotidiano - Union Trento - Official Site % %","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.uniontrento.it\/index.php\/giornale-il-t-quotidiano\/","og_locale":"it_IT","og_type":"article","og_title":"Giornale Il T Quotidiano - Union Trento - Official Site % %","og_url":"https:\/\/www.uniontrento.it\/index.php\/giornale-il-t-quotidiano\/","og_site_name":"Union Trento - Official Site","article_publisher":"https:\/\/www.facebook.com\/UnionTrento","article_published_time":"2025-08-13T13:47:54+00:00","article_modified_time":"2025-08-13T13:47:55+00:00","og_image":[{"width":1218,"height":867,"url":"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/08\/Panco-1.png","type":"image\/png"}],"author":"uniontrento_gestioneweb","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"uniontrento_gestioneweb","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.uniontrento.it\/index.php\/giornale-il-t-quotidiano\/#article","isPartOf":{"@id":"https:\/\/www.uniontrento.it\/index.php\/giornale-il-t-quotidiano\/"},"author":{"name":"uniontrento_gestioneweb","@id":"https:\/\/www.uniontrento.it\/#\/schema\/person\/0c6508e49b2f6ca9fb8db40660ad9188"},"headline":"Giornale Il T Quotidiano","datePublished":"2025-08-13T13:47:54+00:00","dateModified":"2025-08-13T13:47:55+00:00","mainEntityOfPage":{"@id":"https:\/\/www.uniontrento.it\/index.php\/giornale-il-t-quotidiano\/"},"wordCount":4,"publisher":{"@id":"https:\/\/www.uniontrento.it\/#organization"},"image":{"@id":"https:\/\/www.uniontrento.it\/index.php\/giornale-il-t-quotidiano\/#primaryimage"},"thumbnailUrl":"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/08\/Panco-1.png","articleSection":["Rassegna stampa - Union Trento Ravinense"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.uniontrento.it\/index.php\/giornale-il-t-quotidiano\/","url":"https:\/\/www.uniontrento.it\/index.php\/giornale-il-t-quotidiano\/","name":"Giornale Il T Quotidiano - Union Trento - Official Site % %","isPartOf":{"@id":"https:\/\/www.uniontrento.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.uniontrento.it\/index.php\/giornale-il-t-quotidiano\/#primaryimage"},"image":{"@id":"https:\/\/www.uniontrento.it\/index.php\/giornale-il-t-quotidiano\/#primaryimage"},"thumbnailUrl":"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/08\/Panco-1.png","datePublished":"2025-08-13T13:47:54+00:00","dateModified":"2025-08-13T13:47:55+00:00","breadcrumb":{"@id":"https:\/\/www.uniontrento.it\/index.php\/giornale-il-t-quotidiano\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.uniontrento.it\/index.php\/giornale-il-t-quotidiano\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.uniontrento.it\/index.php\/giornale-il-t-quotidiano\/#primaryimage","url":"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/08\/Panco-1.png","contentUrl":"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/08\/Panco-1.png","width":1218,"height":867},{"@type":"BreadcrumbList","@id":"https:\/\/www.uniontrento.it\/index.php\/giornale-il-t-quotidiano\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.uniontrento.it\/"},{"@type":"ListItem","position":2,"name":"Giornale Il T Quotidiano"}]},{"@type":"WebSite","@id":"https:\/\/www.uniontrento.it\/#website","url":"https:\/\/www.uniontrento.it\/","name":"Union Trento","description":"Sito ufficiale Union Trento, nuovo progetto calcistico nella citt\u00e0 di Trento che incorpora le societ\u00e0 Mattarello Calcio e U.S. Ravinense","publisher":{"@id":"https:\/\/www.uniontrento.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.uniontrento.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.uniontrento.it\/#organization","name":"Union Trento","url":"https:\/\/www.uniontrento.it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.uniontrento.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2024\/08\/LogoUnionTrento_col.png","contentUrl":"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2024\/08\/LogoUnionTrento_col.png","width":924,"height":1198,"caption":"Union Trento"},"image":{"@id":"https:\/\/www.uniontrento.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/UnionTrento","https:\/\/www.instagram.com\/union_trento\/"]},{"@type":"Person","@id":"https:\/\/www.uniontrento.it\/#\/schema\/person\/0c6508e49b2f6ca9fb8db40660ad9188","name":"uniontrento_gestioneweb","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/78920b74754d8edf774bf4174042990997a633859907c226bc7056921d103849?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/78920b74754d8edf774bf4174042990997a633859907c226bc7056921d103849?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/78920b74754d8edf774bf4174042990997a633859907c226bc7056921d103849?s=96&d=mm&r=g","caption":"uniontrento_gestioneweb"},"url":"https:\/\/www.uniontrento.it\/index.php\/author\/uniontrento_gestioneweb\/"}]}},"_links":{"self":[{"href":"https:\/\/www.uniontrento.it\/index.php\/wp-json\/wp\/v2\/posts\/6270","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uniontrento.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uniontrento.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uniontrento.it\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uniontrento.it\/index.php\/wp-json\/wp\/v2\/comments?post=6270"}],"version-history":[{"count":1,"href":"https:\/\/www.uniontrento.it\/index.php\/wp-json\/wp\/v2\/posts\/6270\/revisions"}],"predecessor-version":[{"id":6273,"href":"https:\/\/www.uniontrento.it\/index.php\/wp-json\/wp\/v2\/posts\/6270\/revisions\/6273"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.uniontrento.it\/index.php\/wp-json\/wp\/v2\/media\/6272"}],"wp:attachment":[{"href":"https:\/\/www.uniontrento.it\/index.php\/wp-json\/wp\/v2\/media?parent=6270"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uniontrento.it\/index.php\/wp-json\/wp\/v2\/categories?post=6270"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uniontrento.it\/index.php\/wp-json\/wp\/v2\/tags?post=6270"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}