{"id":5452,"date":"2025-06-13T15:01:34","date_gmt":"2025-06-13T13:01:34","guid":{"rendered":"https:\/\/www.uniontrento.it\/?p=5452"},"modified":"2025-06-13T15:01:36","modified_gmt":"2025-06-13T13:01:36","slug":"mentalita-vincente-con-kaziyski-pecchia-micciche-e-pancheri","status":"publish","type":"post","link":"https:\/\/www.uniontrento.it\/index.php\/mentalita-vincente-con-kaziyski-pecchia-micciche-e-pancheri\/","title":{"rendered":"Mentalit\u00e0 vincente con Kaziyski, Pecchia, Miccich\u00e8 e Pancheri"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Talk show di grande prestigio ieri sera presso il centro sportivo di Ravina, ospiti della serata la leggenda del volley Matey Kaziyski, l&#8217;ala della Aquila Basket Andrea Pecchia, il capitano del Trento Rugby Davide Miccich\u00e8 e il capitano di Union Trento Andrea Pancheri.<\/h2>\n\n\n\n<p>Ieri sera \u00e8 successo qualcosa di speciale. Un evento che non ha solo celebrato lo sport, ma la mentalit\u00e0 che lo alimenta, fatta di impegno, rispetto, resilienza e spirito di squadra. Una chiacchierata da bere tutta in un fiato per il folto e illustre pubblico accorso al centro sportivo di Ravina, diretta dalla magistrale professionalit\u00e0 di Danilo Pasqualino, con dei grandissimi personaggi dello sport e una vera e propria leggenda dello &#8230;  Matey Kaziyski. <\/p>\n\n\n\n<p>I racconti di Andrea Pecchia, Matey Kaziyski, Davide Miccich\u00e8 e Andrea Pancheri sono entrati con un devastante coinvolgimento in tutti coloro che hanno avuto il piacere di ascoltarli. Racconti di vittorie e di sconfitte, ma soprattutto di uomini di sport che hanno saputo imparare a vincere dalle grandi delusioni.<\/p>\n\n\n\n<p>Union Trento desidera ringraziare gli ospiti che sono intervenuti ed hanno impreziosito una serata davvero unica<\/p>\n\n\n\n<p>\ud83c\udfd0 Matey Kaziyski<br>\ud83c\udfc0 Andrea Pecchia<br>\ud83c\udfc8 Davide Miccich\u00e8<br>\u26bd Andrea Pancheri<\/p>\n\n\n\n<p> <\/p>\n\n\n\n<p><a href=\"https:\/\/www.facebook.com\/media\/set\/?vanity=UnionTrento&amp;set=a.1486153599396532&amp;locale=it_IT\">FOTO GALLERY<\/a><\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"5475\" src=\"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/06\/SERATACAMPIONI-13-1-1024x683.jpg\" alt=\"\" class=\"wp-image-5475\" srcset=\"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/06\/SERATACAMPIONI-13-1-1024x683.jpg 1024w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/06\/SERATACAMPIONI-13-1-300x200.jpg 300w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/06\/SERATACAMPIONI-13-1-768x512.jpg 768w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/06\/SERATACAMPIONI-13-1-1536x1024.jpg 1536w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/06\/SERATACAMPIONI-13-1-2048x1365.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"5474\" src=\"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/06\/SERATACAMPIONI-29-1024x683.jpg\" alt=\"\" class=\"wp-image-5474\" srcset=\"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/06\/SERATACAMPIONI-29-1024x683.jpg 1024w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/06\/SERATACAMPIONI-29-300x200.jpg 300w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/06\/SERATACAMPIONI-29-768x512.jpg 768w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/06\/SERATACAMPIONI-29-1536x1024.jpg 1536w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/06\/SERATACAMPIONI-29-2048x1365.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"5473\" src=\"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/06\/SERATACAMPIONI-33-1024x683.jpg\" alt=\"\" class=\"wp-image-5473\" srcset=\"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/06\/SERATACAMPIONI-33-1024x683.jpg 1024w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/06\/SERATACAMPIONI-33-300x200.jpg 300w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/06\/SERATACAMPIONI-33-768x512.jpg 768w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/06\/SERATACAMPIONI-33-1536x1024.jpg 1536w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/06\/SERATACAMPIONI-33-2048x1365.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"5477\" src=\"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/06\/SERATACAMPIONI-22-1-1024x683.jpg\" alt=\"\" class=\"wp-image-5477\" srcset=\"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/06\/SERATACAMPIONI-22-1-1024x683.jpg 1024w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/06\/SERATACAMPIONI-22-1-300x200.jpg 300w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/06\/SERATACAMPIONI-22-1-768x512.jpg 768w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/06\/SERATACAMPIONI-22-1-1536x1024.jpg 1536w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/06\/SERATACAMPIONI-22-1-2048x1365.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Talk show di grande prestigio ieri sera presso il centro sportivo di Ravina, ospiti della serata la leggenda del volley Matey Kaziyski, l&#8217;ala della Aquila Basket Andrea Pecchia, il capitano del Trento Rugby Davide Miccich\u00e8 e il capitano di Union Trento Andrea Pancheri. Ieri sera \u00e8 successo qualcosa di speciale. Un evento che non ha [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":5472,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":["post-5452","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-societa"],"blocksy_meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mentalit\u00e0 vincente con Kaziyski, Pecchia, Miccich\u00e8 e Pancheri - Union Trento - Official Site % %<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.uniontrento.it\/index.php\/mentalita-vincente-con-kaziyski-pecchia-micciche-e-pancheri\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mentalit\u00e0 vincente con Kaziyski, Pecchia, Miccich\u00e8 e Pancheri - Union Trento - Official Site % %\" \/>\n<meta property=\"og:description\" content=\"Talk show di grande prestigio ieri sera presso il centro sportivo di Ravina, ospiti della serata la leggenda del volley Matey Kaziyski, l&#8217;ala della Aquila Basket Andrea Pecchia, il capitano del Trento Rugby Davide Miccich\u00e8 e il capitano di Union Trento Andrea Pancheri. Ieri sera \u00e8 successo qualcosa di speciale. Un evento che non ha [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.uniontrento.it\/index.php\/mentalita-vincente-con-kaziyski-pecchia-micciche-e-pancheri\/\" \/>\n<meta property=\"og:site_name\" content=\"Union Trento - Official Site\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/UnionTrento\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-13T13:01:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-13T13:01:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/06\/SERATACAMPIONI-1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"uniontrento_gestioneweb\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"uniontrento_gestioneweb\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/index.php\\\/mentalita-vincente-con-kaziyski-pecchia-micciche-e-pancheri\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/index.php\\\/mentalita-vincente-con-kaziyski-pecchia-micciche-e-pancheri\\\/\"},\"author\":{\"name\":\"uniontrento_gestioneweb\",\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/#\\\/schema\\\/person\\\/0c6508e49b2f6ca9fb8db40660ad9188\"},\"headline\":\"Mentalit\u00e0 vincente con Kaziyski, Pecchia, Miccich\u00e8 e Pancheri\",\"datePublished\":\"2025-06-13T13:01:34+00:00\",\"dateModified\":\"2025-06-13T13:01:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/index.php\\\/mentalita-vincente-con-kaziyski-pecchia-micciche-e-pancheri\\\/\"},\"wordCount\":199,\"publisher\":{\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/index.php\\\/mentalita-vincente-con-kaziyski-pecchia-micciche-e-pancheri\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.uniontrento.it\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/SERATACAMPIONI-1-scaled.jpg\",\"articleSection\":[\"News Union Trento Societ\u00e0\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/index.php\\\/mentalita-vincente-con-kaziyski-pecchia-micciche-e-pancheri\\\/\",\"url\":\"https:\\\/\\\/www.uniontrento.it\\\/index.php\\\/mentalita-vincente-con-kaziyski-pecchia-micciche-e-pancheri\\\/\",\"name\":\"Mentalit\u00e0 vincente con Kaziyski, Pecchia, Miccich\u00e8 e Pancheri - Union Trento - Official Site % %\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/index.php\\\/mentalita-vincente-con-kaziyski-pecchia-micciche-e-pancheri\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/index.php\\\/mentalita-vincente-con-kaziyski-pecchia-micciche-e-pancheri\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.uniontrento.it\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/SERATACAMPIONI-1-scaled.jpg\",\"datePublished\":\"2025-06-13T13:01:34+00:00\",\"dateModified\":\"2025-06-13T13:01:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/index.php\\\/mentalita-vincente-con-kaziyski-pecchia-micciche-e-pancheri\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.uniontrento.it\\\/index.php\\\/mentalita-vincente-con-kaziyski-pecchia-micciche-e-pancheri\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/index.php\\\/mentalita-vincente-con-kaziyski-pecchia-micciche-e-pancheri\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.uniontrento.it\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/SERATACAMPIONI-1-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.uniontrento.it\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/SERATACAMPIONI-1-scaled.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/index.php\\\/mentalita-vincente-con-kaziyski-pecchia-micciche-e-pancheri\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.uniontrento.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mentalit\u00e0 vincente con Kaziyski, Pecchia, Miccich\u00e8 e Pancheri\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/#website\",\"url\":\"https:\\\/\\\/www.uniontrento.it\\\/\",\"name\":\"Union Trento\",\"description\":\"Sito ufficiale Union Trento, nuovo progetto calcistico nella citt\u00e0 di Trento che incorpora le societ\u00e0 Mattarello Calcio e U.S. Ravinense\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.uniontrento.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/#organization\",\"name\":\"Union Trento\",\"url\":\"https:\\\/\\\/www.uniontrento.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.uniontrento.it\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/LogoUnionTrento_col.png\",\"contentUrl\":\"https:\\\/\\\/www.uniontrento.it\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/LogoUnionTrento_col.png\",\"width\":924,\"height\":1198,\"caption\":\"Union Trento\"},\"image\":{\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/UnionTrento\",\"https:\\\/\\\/www.instagram.com\\\/union_trento\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/#\\\/schema\\\/person\\\/0c6508e49b2f6ca9fb8db40660ad9188\",\"name\":\"uniontrento_gestioneweb\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/78920b74754d8edf774bf4174042990997a633859907c226bc7056921d103849?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/78920b74754d8edf774bf4174042990997a633859907c226bc7056921d103849?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/78920b74754d8edf774bf4174042990997a633859907c226bc7056921d103849?s=96&d=mm&r=g\",\"caption\":\"uniontrento_gestioneweb\"},\"url\":\"https:\\\/\\\/www.uniontrento.it\\\/index.php\\\/author\\\/uniontrento_gestioneweb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mentalit\u00e0 vincente con Kaziyski, Pecchia, Miccich\u00e8 e Pancheri - Union Trento - Official Site % %","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.uniontrento.it\/index.php\/mentalita-vincente-con-kaziyski-pecchia-micciche-e-pancheri\/","og_locale":"it_IT","og_type":"article","og_title":"Mentalit\u00e0 vincente con Kaziyski, Pecchia, Miccich\u00e8 e Pancheri - Union Trento - Official Site % %","og_description":"Talk show di grande prestigio ieri sera presso il centro sportivo di Ravina, ospiti della serata la leggenda del volley Matey Kaziyski, l&#8217;ala della Aquila Basket Andrea Pecchia, il capitano del Trento Rugby Davide Miccich\u00e8 e il capitano di Union Trento Andrea Pancheri. Ieri sera \u00e8 successo qualcosa di speciale. Un evento che non ha [&hellip;]","og_url":"https:\/\/www.uniontrento.it\/index.php\/mentalita-vincente-con-kaziyski-pecchia-micciche-e-pancheri\/","og_site_name":"Union Trento - Official Site","article_publisher":"https:\/\/www.facebook.com\/UnionTrento","article_published_time":"2025-06-13T13:01:34+00:00","article_modified_time":"2025-06-13T13:01:36+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/06\/SERATACAMPIONI-1-scaled.jpg","type":"image\/jpeg"}],"author":"uniontrento_gestioneweb","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"uniontrento_gestioneweb","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.uniontrento.it\/index.php\/mentalita-vincente-con-kaziyski-pecchia-micciche-e-pancheri\/#article","isPartOf":{"@id":"https:\/\/www.uniontrento.it\/index.php\/mentalita-vincente-con-kaziyski-pecchia-micciche-e-pancheri\/"},"author":{"name":"uniontrento_gestioneweb","@id":"https:\/\/www.uniontrento.it\/#\/schema\/person\/0c6508e49b2f6ca9fb8db40660ad9188"},"headline":"Mentalit\u00e0 vincente con Kaziyski, Pecchia, Miccich\u00e8 e Pancheri","datePublished":"2025-06-13T13:01:34+00:00","dateModified":"2025-06-13T13:01:36+00:00","mainEntityOfPage":{"@id":"https:\/\/www.uniontrento.it\/index.php\/mentalita-vincente-con-kaziyski-pecchia-micciche-e-pancheri\/"},"wordCount":199,"publisher":{"@id":"https:\/\/www.uniontrento.it\/#organization"},"image":{"@id":"https:\/\/www.uniontrento.it\/index.php\/mentalita-vincente-con-kaziyski-pecchia-micciche-e-pancheri\/#primaryimage"},"thumbnailUrl":"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/06\/SERATACAMPIONI-1-scaled.jpg","articleSection":["News Union Trento Societ\u00e0"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.uniontrento.it\/index.php\/mentalita-vincente-con-kaziyski-pecchia-micciche-e-pancheri\/","url":"https:\/\/www.uniontrento.it\/index.php\/mentalita-vincente-con-kaziyski-pecchia-micciche-e-pancheri\/","name":"Mentalit\u00e0 vincente con Kaziyski, Pecchia, Miccich\u00e8 e Pancheri - Union Trento - Official Site % %","isPartOf":{"@id":"https:\/\/www.uniontrento.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.uniontrento.it\/index.php\/mentalita-vincente-con-kaziyski-pecchia-micciche-e-pancheri\/#primaryimage"},"image":{"@id":"https:\/\/www.uniontrento.it\/index.php\/mentalita-vincente-con-kaziyski-pecchia-micciche-e-pancheri\/#primaryimage"},"thumbnailUrl":"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/06\/SERATACAMPIONI-1-scaled.jpg","datePublished":"2025-06-13T13:01:34+00:00","dateModified":"2025-06-13T13:01:36+00:00","breadcrumb":{"@id":"https:\/\/www.uniontrento.it\/index.php\/mentalita-vincente-con-kaziyski-pecchia-micciche-e-pancheri\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.uniontrento.it\/index.php\/mentalita-vincente-con-kaziyski-pecchia-micciche-e-pancheri\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.uniontrento.it\/index.php\/mentalita-vincente-con-kaziyski-pecchia-micciche-e-pancheri\/#primaryimage","url":"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/06\/SERATACAMPIONI-1-scaled.jpg","contentUrl":"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/06\/SERATACAMPIONI-1-scaled.jpg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/www.uniontrento.it\/index.php\/mentalita-vincente-con-kaziyski-pecchia-micciche-e-pancheri\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.uniontrento.it\/"},{"@type":"ListItem","position":2,"name":"Mentalit\u00e0 vincente con Kaziyski, Pecchia, Miccich\u00e8 e Pancheri"}]},{"@type":"WebSite","@id":"https:\/\/www.uniontrento.it\/#website","url":"https:\/\/www.uniontrento.it\/","name":"Union Trento","description":"Sito ufficiale Union Trento, nuovo progetto calcistico nella citt\u00e0 di Trento che incorpora le societ\u00e0 Mattarello Calcio e U.S. Ravinense","publisher":{"@id":"https:\/\/www.uniontrento.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.uniontrento.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.uniontrento.it\/#organization","name":"Union Trento","url":"https:\/\/www.uniontrento.it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.uniontrento.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2024\/08\/LogoUnionTrento_col.png","contentUrl":"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2024\/08\/LogoUnionTrento_col.png","width":924,"height":1198,"caption":"Union Trento"},"image":{"@id":"https:\/\/www.uniontrento.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/UnionTrento","https:\/\/www.instagram.com\/union_trento\/"]},{"@type":"Person","@id":"https:\/\/www.uniontrento.it\/#\/schema\/person\/0c6508e49b2f6ca9fb8db40660ad9188","name":"uniontrento_gestioneweb","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/78920b74754d8edf774bf4174042990997a633859907c226bc7056921d103849?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/78920b74754d8edf774bf4174042990997a633859907c226bc7056921d103849?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/78920b74754d8edf774bf4174042990997a633859907c226bc7056921d103849?s=96&d=mm&r=g","caption":"uniontrento_gestioneweb"},"url":"https:\/\/www.uniontrento.it\/index.php\/author\/uniontrento_gestioneweb\/"}]}},"_links":{"self":[{"href":"https:\/\/www.uniontrento.it\/index.php\/wp-json\/wp\/v2\/posts\/5452","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uniontrento.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uniontrento.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uniontrento.it\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uniontrento.it\/index.php\/wp-json\/wp\/v2\/comments?post=5452"}],"version-history":[{"count":1,"href":"https:\/\/www.uniontrento.it\/index.php\/wp-json\/wp\/v2\/posts\/5452\/revisions"}],"predecessor-version":[{"id":5478,"href":"https:\/\/www.uniontrento.it\/index.php\/wp-json\/wp\/v2\/posts\/5452\/revisions\/5478"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.uniontrento.it\/index.php\/wp-json\/wp\/v2\/media\/5472"}],"wp:attachment":[{"href":"https:\/\/www.uniontrento.it\/index.php\/wp-json\/wp\/v2\/media?parent=5452"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uniontrento.it\/index.php\/wp-json\/wp\/v2\/categories?post=5452"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uniontrento.it\/index.php\/wp-json\/wp\/v2\/tags?post=5452"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}