{"id":5161,"date":"2025-05-06T15:11:44","date_gmt":"2025-05-06T13:11:44","guid":{"rendered":"https:\/\/www.uniontrento.it\/?p=5161"},"modified":"2025-05-06T15:11:44","modified_gmt":"2025-05-06T13:11:44","slug":"brutta-sconfitta-per-la-ravinense","status":"publish","type":"post","link":"https:\/\/www.uniontrento.it\/index.php\/brutta-sconfitta-per-la-ravinense\/","title":{"rendered":"Brutta sconfitta per la Ravinense"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">La Ravinense cade con la retrocessa Bassa Anaunia e compromette i sogni di primato <\/h2>\n\n\n\n<p>Dopo un primo tempo di dominio totale del campo, apertosi con il vantaggio ad opera di Ferrari, i biancorossi si suicidano in meno di 5&#8242; regalando il vantaggio alla Bassa che a met\u00e0 ripresa su un contropiede trovano anche il gol del definitivo 3 a 1. Sconfitta inopinata e inaspettata che compromette seriamente le velleit\u00e0 di promozione diretta della Ravinense.<\/p>\n\n\n\n<p>Formazioni:<br>Ravinense : Stefani, Tomaselli, Nardelli (dal 55&#8242; Rizzon), Ferrari, Gretter, Dsiri (dal 55&#8242; Coslop),Bordin (dal 20&#8242; Bisognin), Pancheri, Barbetti, Pedrotti (dal 65&#8242; Valentini, Zanotti. A disposizione: Tomasi, Coslop, Maran, Ferraris.<br>All: Melone<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"705\" src=\"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/05\/UNIONTRENTOBORGO-197-1024x705.jpg\" alt=\"\" class=\"wp-image-5162\" style=\"width:465px;height:auto\" srcset=\"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/05\/UNIONTRENTOBORGO-197-1024x705.jpg 1024w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/05\/UNIONTRENTOBORGO-197-300x206.jpg 300w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/05\/UNIONTRENTOBORGO-197-768x529.jpg 768w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/05\/UNIONTRENTOBORGO-197-1536x1057.jpg 1536w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/05\/UNIONTRENTOBORGO-197-2048x1409.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>La Ravinense cade con la retrocessa Bassa Anaunia e compromette i sogni di primato Dopo un primo tempo di dominio totale del campo, apertosi con il vantaggio ad opera di Ferrari, i biancorossi si suicidano in meno di 5&#8242; regalando il vantaggio alla Bassa che a met\u00e0 ripresa su un contropiede trovano anche il gol [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":5162,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-5161","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ravinense"],"blocksy_meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Brutta sconfitta per la Ravinense - Union Trento - Official Site % %<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.uniontrento.it\/index.php\/brutta-sconfitta-per-la-ravinense\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Brutta sconfitta per la Ravinense - Union Trento - Official Site % %\" \/>\n<meta property=\"og:description\" content=\"La Ravinense cade con la retrocessa Bassa Anaunia e compromette i sogni di primato Dopo un primo tempo di dominio totale del campo, apertosi con il vantaggio ad opera di Ferrari, i biancorossi si suicidano in meno di 5&#8242; regalando il vantaggio alla Bassa che a met\u00e0 ripresa su un contropiede trovano anche il gol [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.uniontrento.it\/index.php\/brutta-sconfitta-per-la-ravinense\/\" \/>\n<meta property=\"og:site_name\" content=\"Union Trento - Official Site\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/UnionTrento\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-06T13:11:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/05\/UNIONTRENTOBORGO-197-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1762\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"uniontrento_gestioneweb\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"uniontrento_gestioneweb\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/index.php\\\/brutta-sconfitta-per-la-ravinense\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/index.php\\\/brutta-sconfitta-per-la-ravinense\\\/\"},\"author\":{\"name\":\"uniontrento_gestioneweb\",\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/#\\\/schema\\\/person\\\/0c6508e49b2f6ca9fb8db40660ad9188\"},\"headline\":\"Brutta sconfitta per la Ravinense\",\"datePublished\":\"2025-05-06T13:11:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/index.php\\\/brutta-sconfitta-per-la-ravinense\\\/\"},\"wordCount\":105,\"publisher\":{\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/index.php\\\/brutta-sconfitta-per-la-ravinense\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.uniontrento.it\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/UNIONTRENTOBORGO-197-scaled.jpg\",\"articleSection\":[\"News Union Trento Ravinense\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/index.php\\\/brutta-sconfitta-per-la-ravinense\\\/\",\"url\":\"https:\\\/\\\/www.uniontrento.it\\\/index.php\\\/brutta-sconfitta-per-la-ravinense\\\/\",\"name\":\"Brutta sconfitta per la Ravinense - Union Trento - Official Site % %\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/index.php\\\/brutta-sconfitta-per-la-ravinense\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/index.php\\\/brutta-sconfitta-per-la-ravinense\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.uniontrento.it\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/UNIONTRENTOBORGO-197-scaled.jpg\",\"datePublished\":\"2025-05-06T13:11:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/index.php\\\/brutta-sconfitta-per-la-ravinense\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.uniontrento.it\\\/index.php\\\/brutta-sconfitta-per-la-ravinense\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/index.php\\\/brutta-sconfitta-per-la-ravinense\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.uniontrento.it\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/UNIONTRENTOBORGO-197-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.uniontrento.it\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/UNIONTRENTOBORGO-197-scaled.jpg\",\"width\":2560,\"height\":1762},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/index.php\\\/brutta-sconfitta-per-la-ravinense\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.uniontrento.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Brutta sconfitta per la Ravinense\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/#website\",\"url\":\"https:\\\/\\\/www.uniontrento.it\\\/\",\"name\":\"Union Trento\",\"description\":\"Sito ufficiale Union Trento, nuovo progetto calcistico nella citt\u00e0 di Trento che incorpora le societ\u00e0 Mattarello Calcio e U.S. Ravinense\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.uniontrento.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/#organization\",\"name\":\"Union Trento\",\"url\":\"https:\\\/\\\/www.uniontrento.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.uniontrento.it\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/LogoUnionTrento_col.png\",\"contentUrl\":\"https:\\\/\\\/www.uniontrento.it\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/LogoUnionTrento_col.png\",\"width\":924,\"height\":1198,\"caption\":\"Union Trento\"},\"image\":{\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/UnionTrento\",\"https:\\\/\\\/www.instagram.com\\\/union_trento\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/#\\\/schema\\\/person\\\/0c6508e49b2f6ca9fb8db40660ad9188\",\"name\":\"uniontrento_gestioneweb\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/78920b74754d8edf774bf4174042990997a633859907c226bc7056921d103849?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/78920b74754d8edf774bf4174042990997a633859907c226bc7056921d103849?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/78920b74754d8edf774bf4174042990997a633859907c226bc7056921d103849?s=96&d=mm&r=g\",\"caption\":\"uniontrento_gestioneweb\"},\"url\":\"https:\\\/\\\/www.uniontrento.it\\\/index.php\\\/author\\\/uniontrento_gestioneweb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Brutta sconfitta per la Ravinense - Union Trento - Official Site % %","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.uniontrento.it\/index.php\/brutta-sconfitta-per-la-ravinense\/","og_locale":"it_IT","og_type":"article","og_title":"Brutta sconfitta per la Ravinense - Union Trento - Official Site % %","og_description":"La Ravinense cade con la retrocessa Bassa Anaunia e compromette i sogni di primato Dopo un primo tempo di dominio totale del campo, apertosi con il vantaggio ad opera di Ferrari, i biancorossi si suicidano in meno di 5&#8242; regalando il vantaggio alla Bassa che a met\u00e0 ripresa su un contropiede trovano anche il gol [&hellip;]","og_url":"https:\/\/www.uniontrento.it\/index.php\/brutta-sconfitta-per-la-ravinense\/","og_site_name":"Union Trento - Official Site","article_publisher":"https:\/\/www.facebook.com\/UnionTrento","article_published_time":"2025-05-06T13:11:44+00:00","og_image":[{"width":2560,"height":1762,"url":"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/05\/UNIONTRENTOBORGO-197-scaled.jpg","type":"image\/jpeg"}],"author":"uniontrento_gestioneweb","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"uniontrento_gestioneweb","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.uniontrento.it\/index.php\/brutta-sconfitta-per-la-ravinense\/#article","isPartOf":{"@id":"https:\/\/www.uniontrento.it\/index.php\/brutta-sconfitta-per-la-ravinense\/"},"author":{"name":"uniontrento_gestioneweb","@id":"https:\/\/www.uniontrento.it\/#\/schema\/person\/0c6508e49b2f6ca9fb8db40660ad9188"},"headline":"Brutta sconfitta per la Ravinense","datePublished":"2025-05-06T13:11:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.uniontrento.it\/index.php\/brutta-sconfitta-per-la-ravinense\/"},"wordCount":105,"publisher":{"@id":"https:\/\/www.uniontrento.it\/#organization"},"image":{"@id":"https:\/\/www.uniontrento.it\/index.php\/brutta-sconfitta-per-la-ravinense\/#primaryimage"},"thumbnailUrl":"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/05\/UNIONTRENTOBORGO-197-scaled.jpg","articleSection":["News Union Trento Ravinense"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.uniontrento.it\/index.php\/brutta-sconfitta-per-la-ravinense\/","url":"https:\/\/www.uniontrento.it\/index.php\/brutta-sconfitta-per-la-ravinense\/","name":"Brutta sconfitta per la Ravinense - Union Trento - Official Site % %","isPartOf":{"@id":"https:\/\/www.uniontrento.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.uniontrento.it\/index.php\/brutta-sconfitta-per-la-ravinense\/#primaryimage"},"image":{"@id":"https:\/\/www.uniontrento.it\/index.php\/brutta-sconfitta-per-la-ravinense\/#primaryimage"},"thumbnailUrl":"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/05\/UNIONTRENTOBORGO-197-scaled.jpg","datePublished":"2025-05-06T13:11:44+00:00","breadcrumb":{"@id":"https:\/\/www.uniontrento.it\/index.php\/brutta-sconfitta-per-la-ravinense\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.uniontrento.it\/index.php\/brutta-sconfitta-per-la-ravinense\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.uniontrento.it\/index.php\/brutta-sconfitta-per-la-ravinense\/#primaryimage","url":"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/05\/UNIONTRENTOBORGO-197-scaled.jpg","contentUrl":"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/05\/UNIONTRENTOBORGO-197-scaled.jpg","width":2560,"height":1762},{"@type":"BreadcrumbList","@id":"https:\/\/www.uniontrento.it\/index.php\/brutta-sconfitta-per-la-ravinense\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.uniontrento.it\/"},{"@type":"ListItem","position":2,"name":"Brutta sconfitta per la Ravinense"}]},{"@type":"WebSite","@id":"https:\/\/www.uniontrento.it\/#website","url":"https:\/\/www.uniontrento.it\/","name":"Union Trento","description":"Sito ufficiale Union Trento, nuovo progetto calcistico nella citt\u00e0 di Trento che incorpora le societ\u00e0 Mattarello Calcio e U.S. Ravinense","publisher":{"@id":"https:\/\/www.uniontrento.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.uniontrento.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.uniontrento.it\/#organization","name":"Union Trento","url":"https:\/\/www.uniontrento.it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.uniontrento.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2024\/08\/LogoUnionTrento_col.png","contentUrl":"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2024\/08\/LogoUnionTrento_col.png","width":924,"height":1198,"caption":"Union Trento"},"image":{"@id":"https:\/\/www.uniontrento.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/UnionTrento","https:\/\/www.instagram.com\/union_trento\/"]},{"@type":"Person","@id":"https:\/\/www.uniontrento.it\/#\/schema\/person\/0c6508e49b2f6ca9fb8db40660ad9188","name":"uniontrento_gestioneweb","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/78920b74754d8edf774bf4174042990997a633859907c226bc7056921d103849?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/78920b74754d8edf774bf4174042990997a633859907c226bc7056921d103849?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/78920b74754d8edf774bf4174042990997a633859907c226bc7056921d103849?s=96&d=mm&r=g","caption":"uniontrento_gestioneweb"},"url":"https:\/\/www.uniontrento.it\/index.php\/author\/uniontrento_gestioneweb\/"}]}},"_links":{"self":[{"href":"https:\/\/www.uniontrento.it\/index.php\/wp-json\/wp\/v2\/posts\/5161","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uniontrento.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uniontrento.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uniontrento.it\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uniontrento.it\/index.php\/wp-json\/wp\/v2\/comments?post=5161"}],"version-history":[{"count":1,"href":"https:\/\/www.uniontrento.it\/index.php\/wp-json\/wp\/v2\/posts\/5161\/revisions"}],"predecessor-version":[{"id":5163,"href":"https:\/\/www.uniontrento.it\/index.php\/wp-json\/wp\/v2\/posts\/5161\/revisions\/5163"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.uniontrento.it\/index.php\/wp-json\/wp\/v2\/media\/5162"}],"wp:attachment":[{"href":"https:\/\/www.uniontrento.it\/index.php\/wp-json\/wp\/v2\/media?parent=5161"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uniontrento.it\/index.php\/wp-json\/wp\/v2\/categories?post=5161"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uniontrento.it\/index.php\/wp-json\/wp\/v2\/tags?post=5161"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}