{"id":5077,"date":"2025-04-10T08:58:25","date_gmt":"2025-04-10T06:58:25","guid":{"rendered":"https:\/\/www.uniontrento.it\/?p=5077"},"modified":"2025-04-10T08:58:39","modified_gmt":"2025-04-10T06:58:39","slug":"grande-successo-per-il-nostro-nutrizionista-alfonso-presutto","status":"publish","type":"post","link":"https:\/\/www.uniontrento.it\/index.php\/grande-successo-per-il-nostro-nutrizionista-alfonso-presutto\/","title":{"rendered":"Grande successo per il nostro nutrizionista Alfonso Presutto"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">La serata con il nutrizionista Alfonso Presutto dal titolo &#8220;L&#8217;importanza di una corretta alimentazione all&#8217;interno della prestazione sportiva&#8221; ha riscosso grande successo tra i nostri tesserati<\/h2>\n\n\n\n<p>Pi\u00f9 di 150 i partecipante ieri sera all&#8217;incontro organizzato dal nostro Responsabile del Settore Giovanile Matteo Cont con il nutrizionista Alfonso Presutto. La serata si \u00e8 svolta in due turni, alle 17 inizio dei lavori con i ragazzi della Scuola Calcio e i loro genitori, mentre alle 18 \u00e8 stata la volta dell&#8217;Agonistica. Eccezionale l&#8217;empatia creatasi tra il professor Presutto e i ragazzini, che hanno interagito con domande e racconti personali. Grazie a tutti per la partecipazione.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"5079\" src=\"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0001-768x1024.jpg\" alt=\"\" class=\"wp-image-5079\" srcset=\"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0001-768x1024.jpg 768w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0001-225x300.jpg 225w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0001-1152x1536.jpg 1152w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0001.jpg 1200w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"5081\" src=\"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0002-1024x768.jpg\" alt=\"\" class=\"wp-image-5081\" srcset=\"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0002-1024x768.jpg 1024w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0002-300x225.jpg 300w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0002-768x576.jpg 768w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0002-1536x1152.jpg 1536w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0002.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"5084\" src=\"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0003-1024x768.jpg\" alt=\"\" class=\"wp-image-5084\" srcset=\"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0003-1024x768.jpg 1024w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0003-300x225.jpg 300w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0003-768x576.jpg 768w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0003-1536x1152.jpg 1536w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0003.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"5086\" src=\"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0004-1024x768.jpg\" alt=\"\" class=\"wp-image-5086\" srcset=\"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0004-1024x768.jpg 1024w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0004-300x225.jpg 300w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0004-768x576.jpg 768w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0004-1536x1152.jpg 1536w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0004.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"5089\" src=\"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0005-1024x768.jpg\" alt=\"\" class=\"wp-image-5089\" srcset=\"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0005-1024x768.jpg 1024w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0005-300x225.jpg 300w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0005-768x576.jpg 768w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0005-1536x1152.jpg 1536w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0005.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"5082\" src=\"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0006-768x1024.jpg\" alt=\"\" class=\"wp-image-5082\" srcset=\"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0006-768x1024.jpg 768w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0006-225x300.jpg 225w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0006-1152x1536.jpg 1152w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0006.jpg 1200w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"5088\" src=\"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0007-1024x768.jpg\" alt=\"\" class=\"wp-image-5088\" srcset=\"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0007-1024x768.jpg 1024w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0007-300x225.jpg 300w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0007-768x576.jpg 768w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0007-1536x1152.jpg 1536w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0007.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"5090\" src=\"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0008-1024x768.jpg\" alt=\"\" class=\"wp-image-5090\" srcset=\"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0008-1024x768.jpg 1024w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0008-300x225.jpg 300w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0008-768x576.jpg 768w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0008-1536x1152.jpg 1536w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0008.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"5087\" src=\"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0009-1024x768.jpg\" alt=\"\" class=\"wp-image-5087\" srcset=\"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0009-1024x768.jpg 1024w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0009-300x225.jpg 300w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0009-768x576.jpg 768w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0009-1536x1152.jpg 1536w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0009.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"5085\" src=\"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0010-1024x768.jpg\" alt=\"\" class=\"wp-image-5085\" srcset=\"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0010-1024x768.jpg 1024w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0010-300x225.jpg 300w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0010-768x576.jpg 768w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0010-1536x1152.jpg 1536w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0010.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"5080\" src=\"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0011-1024x768.jpg\" alt=\"\" class=\"wp-image-5080\" srcset=\"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0011-1024x768.jpg 1024w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0011-300x225.jpg 300w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0011-768x576.jpg 768w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0011-1536x1152.jpg 1536w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0011.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"5083\" src=\"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0012-768x1024.jpg\" alt=\"\" class=\"wp-image-5083\" srcset=\"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0012-768x1024.jpg 768w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0012-225x300.jpg 225w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0012-1152x1536.jpg 1152w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0012.jpg 1200w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"5091\" src=\"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0013-768x1024.jpg\" alt=\"\" class=\"wp-image-5091\" srcset=\"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0013-768x1024.jpg 768w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0013-225x300.jpg 225w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0013-1152x1536.jpg 1152w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0013.jpg 1200w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"5097\" src=\"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0014-1024x768.jpg\" alt=\"\" class=\"wp-image-5097\" srcset=\"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0014-1024x768.jpg 1024w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0014-300x225.jpg 300w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0014-768x576.jpg 768w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0014-1536x1152.jpg 1536w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0014.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"5092\" src=\"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0015-1024x768.jpg\" alt=\"\" class=\"wp-image-5092\" srcset=\"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0015-1024x768.jpg 1024w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0015-300x225.jpg 300w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0015-768x576.jpg 768w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0015-1536x1152.jpg 1536w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0015.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"5095\" src=\"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0016-1024x768.jpg\" alt=\"\" class=\"wp-image-5095\" srcset=\"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0016-1024x768.jpg 1024w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0016-300x225.jpg 300w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0016-768x576.jpg 768w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0016-1536x1152.jpg 1536w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0016.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"5099\" src=\"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0017-1024x768.jpg\" alt=\"\" class=\"wp-image-5099\" srcset=\"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0017-1024x768.jpg 1024w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0017-300x225.jpg 300w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0017-768x576.jpg 768w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0017-1536x1152.jpg 1536w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0017.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"5094\" src=\"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0018-1024x768.jpg\" alt=\"\" class=\"wp-image-5094\" srcset=\"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0018-1024x768.jpg 1024w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0018-300x225.jpg 300w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0018-768x576.jpg 768w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0018-1536x1152.jpg 1536w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0018.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"5096\" src=\"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0019-1024x768.jpg\" alt=\"\" class=\"wp-image-5096\" srcset=\"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0019-1024x768.jpg 1024w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0019-300x225.jpg 300w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0019-768x576.jpg 768w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0019-1536x1152.jpg 1536w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0019.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"5100\" src=\"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0020-1024x768.jpg\" alt=\"\" class=\"wp-image-5100\" srcset=\"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0020-1024x768.jpg 1024w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0020-300x225.jpg 300w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0020-768x576.jpg 768w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0020-1536x1152.jpg 1536w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0020.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"5098\" src=\"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0021-1024x768.jpg\" alt=\"\" class=\"wp-image-5098\" srcset=\"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0021-1024x768.jpg 1024w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0021-300x225.jpg 300w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0021-768x576.jpg 768w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0021-1536x1152.jpg 1536w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0021.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"5093\" src=\"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0022-1024x768.jpg\" alt=\"\" class=\"wp-image-5093\" srcset=\"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0022-1024x768.jpg 1024w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0022-300x225.jpg 300w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0022-768x576.jpg 768w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0022-1536x1152.jpg 1536w, https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/IMG-20250410-WA0022.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La serata con il nutrizionista Alfonso Presutto dal titolo &#8220;L&#8217;importanza di una corretta alimentazione all&#8217;interno della prestazione sportiva&#8221; ha riscosso grande successo tra i nostri tesserati Pi\u00f9 di 150 i partecipante ieri sera all&#8217;incontro organizzato dal nostro Responsabile del Settore Giovanile Matteo Cont con il nutrizionista Alfonso Presutto. La serata si \u00e8 svolta in due [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":5078,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[34],"tags":[],"class_list":["post-5077","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sett-giovanile"],"blocksy_meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Grande successo per il nostro nutrizionista Alfonso Presutto - Union Trento - Official Site % %<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.uniontrento.it\/index.php\/grande-successo-per-il-nostro-nutrizionista-alfonso-presutto\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Grande successo per il nostro nutrizionista Alfonso Presutto - Union Trento - Official Site % %\" \/>\n<meta property=\"og:description\" content=\"La serata con il nutrizionista Alfonso Presutto dal titolo &#8220;L&#8217;importanza di una corretta alimentazione all&#8217;interno della prestazione sportiva&#8221; ha riscosso grande successo tra i nostri tesserati Pi\u00f9 di 150 i partecipante ieri sera all&#8217;incontro organizzato dal nostro Responsabile del Settore Giovanile Matteo Cont con il nutrizionista Alfonso Presutto. La serata si \u00e8 svolta in due [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.uniontrento.it\/index.php\/grande-successo-per-il-nostro-nutrizionista-alfonso-presutto\/\" \/>\n<meta property=\"og:site_name\" content=\"Union Trento - Official Site\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/UnionTrento\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-10T06:58:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-10T06:58:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/Immagine-WhatsApp-2025-04-09-ore-14.09.42_69f65d6a.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"uniontrento_gestioneweb\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"uniontrento_gestioneweb\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/index.php\\\/grande-successo-per-il-nostro-nutrizionista-alfonso-presutto\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/index.php\\\/grande-successo-per-il-nostro-nutrizionista-alfonso-presutto\\\/\"},\"author\":{\"name\":\"uniontrento_gestioneweb\",\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/#\\\/schema\\\/person\\\/0c6508e49b2f6ca9fb8db40660ad9188\"},\"headline\":\"Grande successo per il nostro nutrizionista Alfonso Presutto\",\"datePublished\":\"2025-04-10T06:58:25+00:00\",\"dateModified\":\"2025-04-10T06:58:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/index.php\\\/grande-successo-per-il-nostro-nutrizionista-alfonso-presutto\\\/\"},\"wordCount\":111,\"publisher\":{\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/index.php\\\/grande-successo-per-il-nostro-nutrizionista-alfonso-presutto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.uniontrento.it\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Immagine-WhatsApp-2025-04-09-ore-14.09.42_69f65d6a.jpg\",\"articleSection\":[\"News Settore Giovanile\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/index.php\\\/grande-successo-per-il-nostro-nutrizionista-alfonso-presutto\\\/\",\"url\":\"https:\\\/\\\/www.uniontrento.it\\\/index.php\\\/grande-successo-per-il-nostro-nutrizionista-alfonso-presutto\\\/\",\"name\":\"Grande successo per il nostro nutrizionista Alfonso Presutto - Union Trento - Official Site % %\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/index.php\\\/grande-successo-per-il-nostro-nutrizionista-alfonso-presutto\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/index.php\\\/grande-successo-per-il-nostro-nutrizionista-alfonso-presutto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.uniontrento.it\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Immagine-WhatsApp-2025-04-09-ore-14.09.42_69f65d6a.jpg\",\"datePublished\":\"2025-04-10T06:58:25+00:00\",\"dateModified\":\"2025-04-10T06:58:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/index.php\\\/grande-successo-per-il-nostro-nutrizionista-alfonso-presutto\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.uniontrento.it\\\/index.php\\\/grande-successo-per-il-nostro-nutrizionista-alfonso-presutto\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/index.php\\\/grande-successo-per-il-nostro-nutrizionista-alfonso-presutto\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.uniontrento.it\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Immagine-WhatsApp-2025-04-09-ore-14.09.42_69f65d6a.jpg\",\"contentUrl\":\"https:\\\/\\\/www.uniontrento.it\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Immagine-WhatsApp-2025-04-09-ore-14.09.42_69f65d6a.jpg\",\"width\":1600,\"height\":1600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/index.php\\\/grande-successo-per-il-nostro-nutrizionista-alfonso-presutto\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.uniontrento.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Grande successo per il nostro nutrizionista Alfonso Presutto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/#website\",\"url\":\"https:\\\/\\\/www.uniontrento.it\\\/\",\"name\":\"Union Trento\",\"description\":\"Sito ufficiale Union Trento, nuovo progetto calcistico nella citt\u00e0 di Trento che incorpora le societ\u00e0 Mattarello Calcio e U.S. Ravinense\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.uniontrento.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/#organization\",\"name\":\"Union Trento\",\"url\":\"https:\\\/\\\/www.uniontrento.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.uniontrento.it\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/LogoUnionTrento_col.png\",\"contentUrl\":\"https:\\\/\\\/www.uniontrento.it\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/LogoUnionTrento_col.png\",\"width\":924,\"height\":1198,\"caption\":\"Union Trento\"},\"image\":{\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/UnionTrento\",\"https:\\\/\\\/www.instagram.com\\\/union_trento\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/#\\\/schema\\\/person\\\/0c6508e49b2f6ca9fb8db40660ad9188\",\"name\":\"uniontrento_gestioneweb\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/78920b74754d8edf774bf4174042990997a633859907c226bc7056921d103849?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/78920b74754d8edf774bf4174042990997a633859907c226bc7056921d103849?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/78920b74754d8edf774bf4174042990997a633859907c226bc7056921d103849?s=96&d=mm&r=g\",\"caption\":\"uniontrento_gestioneweb\"},\"url\":\"https:\\\/\\\/www.uniontrento.it\\\/index.php\\\/author\\\/uniontrento_gestioneweb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Grande successo per il nostro nutrizionista Alfonso Presutto - Union Trento - Official Site % %","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.uniontrento.it\/index.php\/grande-successo-per-il-nostro-nutrizionista-alfonso-presutto\/","og_locale":"it_IT","og_type":"article","og_title":"Grande successo per il nostro nutrizionista Alfonso Presutto - Union Trento - Official Site % %","og_description":"La serata con il nutrizionista Alfonso Presutto dal titolo &#8220;L&#8217;importanza di una corretta alimentazione all&#8217;interno della prestazione sportiva&#8221; ha riscosso grande successo tra i nostri tesserati Pi\u00f9 di 150 i partecipante ieri sera all&#8217;incontro organizzato dal nostro Responsabile del Settore Giovanile Matteo Cont con il nutrizionista Alfonso Presutto. La serata si \u00e8 svolta in due [&hellip;]","og_url":"https:\/\/www.uniontrento.it\/index.php\/grande-successo-per-il-nostro-nutrizionista-alfonso-presutto\/","og_site_name":"Union Trento - Official Site","article_publisher":"https:\/\/www.facebook.com\/UnionTrento","article_published_time":"2025-04-10T06:58:25+00:00","article_modified_time":"2025-04-10T06:58:39+00:00","og_image":[{"width":1600,"height":1600,"url":"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/Immagine-WhatsApp-2025-04-09-ore-14.09.42_69f65d6a.jpg","type":"image\/jpeg"}],"author":"uniontrento_gestioneweb","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"uniontrento_gestioneweb","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.uniontrento.it\/index.php\/grande-successo-per-il-nostro-nutrizionista-alfonso-presutto\/#article","isPartOf":{"@id":"https:\/\/www.uniontrento.it\/index.php\/grande-successo-per-il-nostro-nutrizionista-alfonso-presutto\/"},"author":{"name":"uniontrento_gestioneweb","@id":"https:\/\/www.uniontrento.it\/#\/schema\/person\/0c6508e49b2f6ca9fb8db40660ad9188"},"headline":"Grande successo per il nostro nutrizionista Alfonso Presutto","datePublished":"2025-04-10T06:58:25+00:00","dateModified":"2025-04-10T06:58:39+00:00","mainEntityOfPage":{"@id":"https:\/\/www.uniontrento.it\/index.php\/grande-successo-per-il-nostro-nutrizionista-alfonso-presutto\/"},"wordCount":111,"publisher":{"@id":"https:\/\/www.uniontrento.it\/#organization"},"image":{"@id":"https:\/\/www.uniontrento.it\/index.php\/grande-successo-per-il-nostro-nutrizionista-alfonso-presutto\/#primaryimage"},"thumbnailUrl":"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/Immagine-WhatsApp-2025-04-09-ore-14.09.42_69f65d6a.jpg","articleSection":["News Settore Giovanile"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.uniontrento.it\/index.php\/grande-successo-per-il-nostro-nutrizionista-alfonso-presutto\/","url":"https:\/\/www.uniontrento.it\/index.php\/grande-successo-per-il-nostro-nutrizionista-alfonso-presutto\/","name":"Grande successo per il nostro nutrizionista Alfonso Presutto - Union Trento - Official Site % %","isPartOf":{"@id":"https:\/\/www.uniontrento.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.uniontrento.it\/index.php\/grande-successo-per-il-nostro-nutrizionista-alfonso-presutto\/#primaryimage"},"image":{"@id":"https:\/\/www.uniontrento.it\/index.php\/grande-successo-per-il-nostro-nutrizionista-alfonso-presutto\/#primaryimage"},"thumbnailUrl":"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/Immagine-WhatsApp-2025-04-09-ore-14.09.42_69f65d6a.jpg","datePublished":"2025-04-10T06:58:25+00:00","dateModified":"2025-04-10T06:58:39+00:00","breadcrumb":{"@id":"https:\/\/www.uniontrento.it\/index.php\/grande-successo-per-il-nostro-nutrizionista-alfonso-presutto\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.uniontrento.it\/index.php\/grande-successo-per-il-nostro-nutrizionista-alfonso-presutto\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.uniontrento.it\/index.php\/grande-successo-per-il-nostro-nutrizionista-alfonso-presutto\/#primaryimage","url":"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/Immagine-WhatsApp-2025-04-09-ore-14.09.42_69f65d6a.jpg","contentUrl":"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/04\/Immagine-WhatsApp-2025-04-09-ore-14.09.42_69f65d6a.jpg","width":1600,"height":1600},{"@type":"BreadcrumbList","@id":"https:\/\/www.uniontrento.it\/index.php\/grande-successo-per-il-nostro-nutrizionista-alfonso-presutto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.uniontrento.it\/"},{"@type":"ListItem","position":2,"name":"Grande successo per il nostro nutrizionista Alfonso Presutto"}]},{"@type":"WebSite","@id":"https:\/\/www.uniontrento.it\/#website","url":"https:\/\/www.uniontrento.it\/","name":"Union Trento","description":"Sito ufficiale Union Trento, nuovo progetto calcistico nella citt\u00e0 di Trento che incorpora le societ\u00e0 Mattarello Calcio e U.S. Ravinense","publisher":{"@id":"https:\/\/www.uniontrento.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.uniontrento.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.uniontrento.it\/#organization","name":"Union Trento","url":"https:\/\/www.uniontrento.it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.uniontrento.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2024\/08\/LogoUnionTrento_col.png","contentUrl":"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2024\/08\/LogoUnionTrento_col.png","width":924,"height":1198,"caption":"Union Trento"},"image":{"@id":"https:\/\/www.uniontrento.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/UnionTrento","https:\/\/www.instagram.com\/union_trento\/"]},{"@type":"Person","@id":"https:\/\/www.uniontrento.it\/#\/schema\/person\/0c6508e49b2f6ca9fb8db40660ad9188","name":"uniontrento_gestioneweb","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/78920b74754d8edf774bf4174042990997a633859907c226bc7056921d103849?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/78920b74754d8edf774bf4174042990997a633859907c226bc7056921d103849?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/78920b74754d8edf774bf4174042990997a633859907c226bc7056921d103849?s=96&d=mm&r=g","caption":"uniontrento_gestioneweb"},"url":"https:\/\/www.uniontrento.it\/index.php\/author\/uniontrento_gestioneweb\/"}]}},"_links":{"self":[{"href":"https:\/\/www.uniontrento.it\/index.php\/wp-json\/wp\/v2\/posts\/5077","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uniontrento.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uniontrento.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uniontrento.it\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uniontrento.it\/index.php\/wp-json\/wp\/v2\/comments?post=5077"}],"version-history":[{"count":1,"href":"https:\/\/www.uniontrento.it\/index.php\/wp-json\/wp\/v2\/posts\/5077\/revisions"}],"predecessor-version":[{"id":5101,"href":"https:\/\/www.uniontrento.it\/index.php\/wp-json\/wp\/v2\/posts\/5077\/revisions\/5101"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.uniontrento.it\/index.php\/wp-json\/wp\/v2\/media\/5078"}],"wp:attachment":[{"href":"https:\/\/www.uniontrento.it\/index.php\/wp-json\/wp\/v2\/media?parent=5077"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uniontrento.it\/index.php\/wp-json\/wp\/v2\/categories?post=5077"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uniontrento.it\/index.php\/wp-json\/wp\/v2\/tags?post=5077"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}