{"id":4696,"date":"2025-02-25T08:49:37","date_gmt":"2025-02-25T07:49:37","guid":{"rendered":"https:\/\/www.uniontrento.it\/?p=4696"},"modified":"2025-02-25T11:44:26","modified_gmt":"2025-02-25T10:44:26","slug":"mattarello-calcio-redival-0-1","status":"publish","type":"post","link":"https:\/\/www.uniontrento.it\/index.php\/mattarello-calcio-redival-0-1\/","title":{"rendered":"Mattarello Calcio &#8211; Redival 0 &#8211; 1"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Sfuma il passaggio alla seconda fase della Coppa Dao <\/h2>\n\n\n\n<p>Prestazione incolore per i ragazzi di Matterello che dopo due buone prove, domenica pomeriggio hanno mancato la qualificazione alla seconda fase della Coppa Dao. Castigati a pochi minuti dalla fine della gara i rossoneri non hanno saputo reagire nei pochi minuti restanti. A parziale giustificazione le numerose assenze importanti alle quali il Mattarello ha dovuto far fronte.<\/p>\n\n\n\n<p><strong>FORMAZIONE:<\/strong> Dal Ri, Merler (dal 76&#8242; Piscitelli) , Ceccarini, Tomasi, Caobelli (dal 71&#8242; Pasetti), Laratta (dal 63&#8242; Nicolosi), Minari, Nardelli, Zanier, Porrovecchio (dal 55&#8242; Zuccaro), Stanchina <strong>A DISPOSIZIONE<\/strong>: Ferretti, Veljij, Daminato<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img decoding=\"async\" src=\"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2024\/08\/Tomasi-Simone-1024x1024.jpg\" alt=\"\" class=\"wp-image-3232\" style=\"width:361px;height:auto\"\/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Sfuma il passaggio alla seconda fase della Coppa Dao Prestazione incolore per i ragazzi di Matterello che dopo due buone prove, domenica pomeriggio hanno mancato la qualificazione alla seconda fase della Coppa Dao. Castigati a pochi minuti dalla fine della gara i rossoneri non hanno saputo reagire nei pochi minuti restanti. A parziale giustificazione le [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":4697,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":["post-4696","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-futuro"],"blocksy_meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mattarello Calcio - Redival 0 - 1 - Union Trento - Official Site % %<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.uniontrento.it\/index.php\/mattarello-calcio-redival-0-1\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mattarello Calcio - Redival 0 - 1 - Union Trento - Official Site % %\" \/>\n<meta property=\"og:description\" content=\"Sfuma il passaggio alla seconda fase della Coppa Dao Prestazione incolore per i ragazzi di Matterello che dopo due buone prove, domenica pomeriggio hanno mancato la qualificazione alla seconda fase della Coppa Dao. Castigati a pochi minuti dalla fine della gara i rossoneri non hanno saputo reagire nei pochi minuti restanti. A parziale giustificazione le [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.uniontrento.it\/index.php\/mattarello-calcio-redival-0-1\/\" \/>\n<meta property=\"og:site_name\" content=\"Union Trento - Official Site\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/UnionTrento\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-25T07:49:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-25T10:44:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/02\/Partita_casa.png\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"uniontrento_gestioneweb\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"uniontrento_gestioneweb\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/index.php\\\/mattarello-calcio-redival-0-1\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/index.php\\\/mattarello-calcio-redival-0-1\\\/\"},\"author\":{\"name\":\"uniontrento_gestioneweb\",\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/#\\\/schema\\\/person\\\/0c6508e49b2f6ca9fb8db40660ad9188\"},\"headline\":\"Mattarello Calcio &#8211; Redival 0 &#8211; 1\",\"datePublished\":\"2025-02-25T07:49:37+00:00\",\"dateModified\":\"2025-02-25T10:44:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/index.php\\\/mattarello-calcio-redival-0-1\\\/\"},\"wordCount\":97,\"publisher\":{\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/index.php\\\/mattarello-calcio-redival-0-1\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.uniontrento.it\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Partita_casa.png\",\"articleSection\":[\"News Union Trento Futuro\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/index.php\\\/mattarello-calcio-redival-0-1\\\/\",\"url\":\"https:\\\/\\\/www.uniontrento.it\\\/index.php\\\/mattarello-calcio-redival-0-1\\\/\",\"name\":\"Mattarello Calcio - Redival 0 - 1 - Union Trento - Official Site % %\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/index.php\\\/mattarello-calcio-redival-0-1\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/index.php\\\/mattarello-calcio-redival-0-1\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.uniontrento.it\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Partita_casa.png\",\"datePublished\":\"2025-02-25T07:49:37+00:00\",\"dateModified\":\"2025-02-25T10:44:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/index.php\\\/mattarello-calcio-redival-0-1\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.uniontrento.it\\\/index.php\\\/mattarello-calcio-redival-0-1\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/index.php\\\/mattarello-calcio-redival-0-1\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.uniontrento.it\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Partita_casa.png\",\"contentUrl\":\"https:\\\/\\\/www.uniontrento.it\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Partita_casa.png\",\"width\":500,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/index.php\\\/mattarello-calcio-redival-0-1\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.uniontrento.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mattarello Calcio &#8211; Redival 0 &#8211; 1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/#website\",\"url\":\"https:\\\/\\\/www.uniontrento.it\\\/\",\"name\":\"Union Trento\",\"description\":\"Sito ufficiale Union Trento, nuovo progetto calcistico nella citt\u00e0 di Trento che incorpora le societ\u00e0 Mattarello Calcio e U.S. Ravinense\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.uniontrento.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/#organization\",\"name\":\"Union Trento\",\"url\":\"https:\\\/\\\/www.uniontrento.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.uniontrento.it\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/LogoUnionTrento_col.png\",\"contentUrl\":\"https:\\\/\\\/www.uniontrento.it\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/LogoUnionTrento_col.png\",\"width\":924,\"height\":1198,\"caption\":\"Union Trento\"},\"image\":{\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/UnionTrento\",\"https:\\\/\\\/www.instagram.com\\\/union_trento\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.uniontrento.it\\\/#\\\/schema\\\/person\\\/0c6508e49b2f6ca9fb8db40660ad9188\",\"name\":\"uniontrento_gestioneweb\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/78920b74754d8edf774bf4174042990997a633859907c226bc7056921d103849?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/78920b74754d8edf774bf4174042990997a633859907c226bc7056921d103849?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/78920b74754d8edf774bf4174042990997a633859907c226bc7056921d103849?s=96&d=mm&r=g\",\"caption\":\"uniontrento_gestioneweb\"},\"url\":\"https:\\\/\\\/www.uniontrento.it\\\/index.php\\\/author\\\/uniontrento_gestioneweb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mattarello Calcio - Redival 0 - 1 - Union Trento - Official Site % %","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.uniontrento.it\/index.php\/mattarello-calcio-redival-0-1\/","og_locale":"it_IT","og_type":"article","og_title":"Mattarello Calcio - Redival 0 - 1 - Union Trento - Official Site % %","og_description":"Sfuma il passaggio alla seconda fase della Coppa Dao Prestazione incolore per i ragazzi di Matterello che dopo due buone prove, domenica pomeriggio hanno mancato la qualificazione alla seconda fase della Coppa Dao. Castigati a pochi minuti dalla fine della gara i rossoneri non hanno saputo reagire nei pochi minuti restanti. A parziale giustificazione le [&hellip;]","og_url":"https:\/\/www.uniontrento.it\/index.php\/mattarello-calcio-redival-0-1\/","og_site_name":"Union Trento - Official Site","article_publisher":"https:\/\/www.facebook.com\/UnionTrento","article_published_time":"2025-02-25T07:49:37+00:00","article_modified_time":"2025-02-25T10:44:26+00:00","og_image":[{"width":500,"height":500,"url":"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/02\/Partita_casa.png","type":"image\/png"}],"author":"uniontrento_gestioneweb","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"uniontrento_gestioneweb","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.uniontrento.it\/index.php\/mattarello-calcio-redival-0-1\/#article","isPartOf":{"@id":"https:\/\/www.uniontrento.it\/index.php\/mattarello-calcio-redival-0-1\/"},"author":{"name":"uniontrento_gestioneweb","@id":"https:\/\/www.uniontrento.it\/#\/schema\/person\/0c6508e49b2f6ca9fb8db40660ad9188"},"headline":"Mattarello Calcio &#8211; Redival 0 &#8211; 1","datePublished":"2025-02-25T07:49:37+00:00","dateModified":"2025-02-25T10:44:26+00:00","mainEntityOfPage":{"@id":"https:\/\/www.uniontrento.it\/index.php\/mattarello-calcio-redival-0-1\/"},"wordCount":97,"publisher":{"@id":"https:\/\/www.uniontrento.it\/#organization"},"image":{"@id":"https:\/\/www.uniontrento.it\/index.php\/mattarello-calcio-redival-0-1\/#primaryimage"},"thumbnailUrl":"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/02\/Partita_casa.png","articleSection":["News Union Trento Futuro"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.uniontrento.it\/index.php\/mattarello-calcio-redival-0-1\/","url":"https:\/\/www.uniontrento.it\/index.php\/mattarello-calcio-redival-0-1\/","name":"Mattarello Calcio - Redival 0 - 1 - Union Trento - Official Site % %","isPartOf":{"@id":"https:\/\/www.uniontrento.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.uniontrento.it\/index.php\/mattarello-calcio-redival-0-1\/#primaryimage"},"image":{"@id":"https:\/\/www.uniontrento.it\/index.php\/mattarello-calcio-redival-0-1\/#primaryimage"},"thumbnailUrl":"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/02\/Partita_casa.png","datePublished":"2025-02-25T07:49:37+00:00","dateModified":"2025-02-25T10:44:26+00:00","breadcrumb":{"@id":"https:\/\/www.uniontrento.it\/index.php\/mattarello-calcio-redival-0-1\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.uniontrento.it\/index.php\/mattarello-calcio-redival-0-1\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.uniontrento.it\/index.php\/mattarello-calcio-redival-0-1\/#primaryimage","url":"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/02\/Partita_casa.png","contentUrl":"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2025\/02\/Partita_casa.png","width":500,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/www.uniontrento.it\/index.php\/mattarello-calcio-redival-0-1\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.uniontrento.it\/"},{"@type":"ListItem","position":2,"name":"Mattarello Calcio &#8211; Redival 0 &#8211; 1"}]},{"@type":"WebSite","@id":"https:\/\/www.uniontrento.it\/#website","url":"https:\/\/www.uniontrento.it\/","name":"Union Trento","description":"Sito ufficiale Union Trento, nuovo progetto calcistico nella citt\u00e0 di Trento che incorpora le societ\u00e0 Mattarello Calcio e U.S. Ravinense","publisher":{"@id":"https:\/\/www.uniontrento.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.uniontrento.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.uniontrento.it\/#organization","name":"Union Trento","url":"https:\/\/www.uniontrento.it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.uniontrento.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2024\/08\/LogoUnionTrento_col.png","contentUrl":"https:\/\/www.uniontrento.it\/wp-content\/uploads\/2024\/08\/LogoUnionTrento_col.png","width":924,"height":1198,"caption":"Union Trento"},"image":{"@id":"https:\/\/www.uniontrento.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/UnionTrento","https:\/\/www.instagram.com\/union_trento\/"]},{"@type":"Person","@id":"https:\/\/www.uniontrento.it\/#\/schema\/person\/0c6508e49b2f6ca9fb8db40660ad9188","name":"uniontrento_gestioneweb","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/78920b74754d8edf774bf4174042990997a633859907c226bc7056921d103849?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/78920b74754d8edf774bf4174042990997a633859907c226bc7056921d103849?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/78920b74754d8edf774bf4174042990997a633859907c226bc7056921d103849?s=96&d=mm&r=g","caption":"uniontrento_gestioneweb"},"url":"https:\/\/www.uniontrento.it\/index.php\/author\/uniontrento_gestioneweb\/"}]}},"_links":{"self":[{"href":"https:\/\/www.uniontrento.it\/index.php\/wp-json\/wp\/v2\/posts\/4696","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uniontrento.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uniontrento.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uniontrento.it\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uniontrento.it\/index.php\/wp-json\/wp\/v2\/comments?post=4696"}],"version-history":[{"count":2,"href":"https:\/\/www.uniontrento.it\/index.php\/wp-json\/wp\/v2\/posts\/4696\/revisions"}],"predecessor-version":[{"id":4706,"href":"https:\/\/www.uniontrento.it\/index.php\/wp-json\/wp\/v2\/posts\/4696\/revisions\/4706"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.uniontrento.it\/index.php\/wp-json\/wp\/v2\/media\/4697"}],"wp:attachment":[{"href":"https:\/\/www.uniontrento.it\/index.php\/wp-json\/wp\/v2\/media?parent=4696"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uniontrento.it\/index.php\/wp-json\/wp\/v2\/categories?post=4696"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uniontrento.it\/index.php\/wp-json\/wp\/v2\/tags?post=4696"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}